{"id":23919,"date":"2020-05-05T23:11:20","date_gmt":"2020-05-06T02:11:20","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=23919"},"modified":"2020-05-05T23:11:20","modified_gmt":"2020-05-06T02:11:20","slug":"suspeito-da-pratica-de-tentativa-de-homicidio-e-preso-com-arma-de-fogo-em-cicero-dantas-ba","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2020\/05\/05\/suspeito-da-pratica-de-tentativa-de-homicidio-e-preso-com-arma-de-fogo-em-cicero-dantas-ba\/","title":{"rendered":"Suspeito da pr\u00e1tica de tentativa de homic\u00eddio, \u00e9 preso com arma de fogo, em C\u00edcero Dantas-BA"},"content":{"rendered":"<p style=\"text-align: justify;\">Na tarde do \u00faltimo domingo, 03, policiais militares da CIPE Nordeste que realizavam rondas de rotina na zona rural de C\u00edcero Dantas-BA, no momento em que transitavam pelo povoado Baixa do Tapuio abordaram um rapaz que se encontrava em situa\u00e7\u00e3o suspeita.<!--more--><\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-thumbnail wp-image-4869 aligncenter\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-720x181.jpg\" alt=\"\" width=\"720\" height=\"181\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre.jpg 720w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-260x65.jpg 260w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-50x13.jpg 50w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-150x38.jpg 150w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>Durante as buscas foi encontrado um rev\u00f3lver cal. 38, contendo quatro muni\u00e7\u00f5es, sob a posse do suspeito.<\/p>\n<p style=\"text-align: justify;\">Diante dos fatos, o abordado que j\u00e1 responde por tentativa de homic\u00eddio, foi conduzido para a Central de Flagrantes em Euclides da Cunha-BA, onde foi registrada a ocorr\u00eancia por Porte Ilegal de Arma de fogo.<\/p>\n<p style=\"text-align: justify;\"><em>Reda\u00e7\u00e3o: Portal Alerta<\/em><\/p>\n<p style=\"text-align: justify;\"><strong><em>#fiqueemcasa<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na tarde do \u00faltimo domingo, 03, policiais militares da CIPE Nordeste que realizavam rondas de rotina na zona rural de C\u00edcero Dantas-BA, no momento em que transitavam pelo povoado Baixa do Tapuio abordaram um rapaz que se encontrava em situa\u00e7\u00e3o suspeita.<\/p>\n","protected":false},"author":2,"featured_media":23920,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4,70,69,32,22],"tags":[75,167,79,83,77,105],"class_list":["post-23919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cicero-dantas","category-destaques","category-noticias2","category-regiao","category-seguranca","tag-cicero-dantas","tag-cipe-nordeste","tag-policia-militar","tag-porte-ilegal-de-arma-de-fogo","tag-preso","tag-tentativa-de-homicidio"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23919"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23919\/revisions"}],"predecessor-version":[{"id":23921,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23919\/revisions\/23921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/23920"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}