{"id":28293,"date":"2020-08-10T20:57:58","date_gmt":"2020-08-10T23:57:58","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=28293"},"modified":"2020-08-10T20:57:58","modified_gmt":"2020-08-10T23:57:58","slug":"eduardo-bolsonaro-entregou-lista-de-antifascistas-aos-eua-diz-deputado-bolsonarista","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2020\/08\/10\/eduardo-bolsonaro-entregou-lista-de-antifascistas-aos-eua-diz-deputado-bolsonarista\/","title":{"rendered":"Eduardo Bolsonaro entregou lista de &#8216;antifascistas&#8217; aos EUA, diz deputado bolsonarista"},"content":{"rendered":"<p style=\"text-align: justify;\">O deputado estadual Douglas Garcia (PTB), um dos principais aliados da fam\u00edlia Bolsonaro em S\u00e3o Paulo, disse \u00e0 Justi\u00e7a que Eduardo Bolsonaro entregou a c\u00f3pia de um dossi\u00ea sobre militantes antifascistas para a Embaixada dos Estados Unidos. As informa\u00e7\u00f5es s\u00e3o do UOL.<!--more--><\/p>\n<p style=\"text-align: justify;\">O juiz Guilherme Ferreira da Cruz, da 45\u00aa Vara C\u00edvel Central da Capital, disse que o deputado n\u00e3o apresentou prova de que as pessoas relacionadas no dossi\u00ea atuem com \u201cviol\u00eancia, pratiquem crimes ou terrorismo\u201d e ainda debochou que as pessoas relacionadas seriam impedidas de visitar a Disneyl\u00e2ndia, lembrando que a listagem foi encaminhada para a embaixada americana. Garcia afirmou no processo que &#8220;o protocolo junto \u00e0 Embaixada dos Estados Unidos foi feito pelo deputado federal Eduardo Bolsonaro&#8221;.<\/p>\n<p style=\"text-align: justify;\">Garcia foi condenado na semana passada a indenizar uma mulher que teve seu nome e dados inseridos nessa lista que, de acordo com postagens feitas pelo pr\u00f3prio Garcia, seriam &#8220;terroristas&#8221;.<\/p>\n<div data-mvc-banner=\"leaderboard\"><\/div>\n<p><script type=\"text\/javascript\"> (function(storeName) { var b = document.createElement('script'); b.type = 'text\/javascript'; b.async = true; b.src = 'https:\/\/www.magazinevoce.com.br\/js\/banner.js?store='+ storeName; var s = document.getElementsByTagName('script')[0]; s.parentNode.insertBefore(b, s); })('Nvscosta'); <\/script><\/p>\n<p style=\"text-align: justify;\">Esse documento \u00e9 diferente do\u00a0relat\u00f3rio do Minist\u00e9rio da Justi\u00e7a, tamb\u00e9m revelado pelo UOL, que listou 579 servidores e professores a favor do antifascismo.<\/p>\n<p style=\"text-align: justify;\">O documento do deputado tem 56 laudas e dados pessoais, inclusive fotografias, de quase mil pessoas. Garcia negou \u00e0 Justi\u00e7a que tivesse participado da elabora\u00e7\u00e3o e da divulga\u00e7\u00e3o do material, mas admitiu que o encaminhou para autoridades..<\/p>\n<p style=\"text-align: justify;\">&#8220;Os grupos subversivos e violentos &#8216;antifas&#8217; atuam em diversos pa\u00edses e, em todos eles, seguem o mesmo modus operandi, que consiste no uso de viol\u00eancia e outros crimes para intimidar, calar e eliminar fisicamente grupos ou indiv\u00edduos n\u00e3o alinhados \u00e0 sua vis\u00e3o pol\u00edtica&#8221;, afirmou o deputado \u00e0 Justi\u00e7a.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Yahoo Not\u00edcias<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado estadual Douglas Garcia (PTB), um dos principais aliados da fam\u00edlia Bolsonaro em S\u00e3o Paulo, disse \u00e0 Justi\u00e7a que Eduardo Bolsonaro entregou a c\u00f3pia de um dossi\u00ea sobre militantes antifascistas para a Embaixada dos Estados Unidos. As informa\u00e7\u00f5es s\u00e3o do UOL.<\/p>\n","protected":false},"author":2,"featured_media":28294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[34,70,69,21,22],"tags":[3843,93,215,2058,327,199],"class_list":["post-28293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaques","category-noticias2","category-politica","category-seguranca","tag-antifacismo","tag-brasil","tag-deputado-federal","tag-eduardo-bolsonaro","tag-eua","tag-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=28293"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28293\/revisions"}],"predecessor-version":[{"id":28295,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28293\/revisions\/28295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/28294"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=28293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=28293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=28293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}