{"id":28359,"date":"2020-08-11T13:49:35","date_gmt":"2020-08-11T16:49:35","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=28359"},"modified":"2020-08-11T13:49:35","modified_gmt":"2020-08-11T16:49:35","slug":"apos-nove-semanas-de-pandemia-antas-ba-registra-o-primeiro-obito-por-covid-19","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2020\/08\/11\/apos-nove-semanas-de-pandemia-antas-ba-registra-o-primeiro-obito-por-covid-19\/","title":{"rendered":"Ap\u00f3s nove semanas de pandemia, Antas-BA registra o primeiro \u00f3bito por Covid-19"},"content":{"rendered":"<p style=\"text-align: justify;\">Ap\u00f3s nove semanas convivendo com a Pandemia, desde o dia 19 de maio, quando registrou o primeiro caso da doen\u00e7a no munic\u00edpio, Antas-BA registrou o primeiro \u00f3bito por conta da Covid-19.<!--more--><\/p>\n<p style=\"text-align: justify;\">A morte foi anunciada no \u00faltimo domingo, 09, atrav\u00e9s de uma nota atribu\u00edda a Secretaria Municipal de Sa\u00fade. De acordo com informa\u00e7\u00f5es o paciente foi identificado como um idoso de 73 anos de idade, que havia testado positivo para a doen\u00e7a, no \u00faltimo dia 27. O idoso chegou a ser transferido para o Hospital Instituto Couto Maia, na capital baiana, onde n\u00e3o resistiu e evoluiu a \u00f3bito.<\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-thumbnail wp-image-4869 aligncenter\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-720x181.jpg\" alt=\"\" width=\"720\" height=\"181\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre.jpg 720w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-260x65.jpg 260w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-50x13.jpg 50w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-150x38.jpg 150w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>At\u00e9 o \u00faltimo s\u00e1bado, 08, Antas, era um dos poucos munic\u00edpios da regi\u00e3o sem registros de \u00f3bitos, restando apenas Banza\u00ea, Cip\u00f3, Heli\u00f3polis e Novo Triunfo, sem registros de mortes por causa do Coronav\u00edrus.<\/p>\n<p>Atualmente Antas se encontra com 103 casos, sendo 32 ativos (31%), 70 curas (68%), e 01 morte (1%).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.portalalerta.com.br\/index.php\/2020\/05\/31\/saiba-como-esta-a-evolucao-do-covid-19-em-antas-ba\/\"><strong>Clique aqui e saiba como est\u00e1 a evolu\u00e7\u00e3o do Covid-19 em Antas-BA<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\"><em>Reda\u00e7\u00e3o: Portal Alerta<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>#fiqueemcasa<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>#usemascaras<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s nove semanas convivendo com a Pandemia, desde o dia 19 de maio, quando registrou o primeiro caso da doen\u00e7a no munic\u00edpio, Antas-BA registrou o primeiro \u00f3bito por conta da Covid-19.<\/p>\n","protected":false},"author":2,"featured_media":24830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5,70,69,32,19],"tags":[100,71,48,49,75,45,3429,3486,46,3454,129,107,44,3724,132,230,169,3828,106,203,120,51,109,88,47,61,111,190],"class_list":["post-28359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antas","category-destaques","category-noticias2","category-regiao","category-saude","tag-adustina","tag-antas","tag-araci","tag-banzae","tag-cicero-dantas","tag-cipo","tag-coronavirus","tag-covid-19","tag-crisopolis","tag-cura","tag-euclides-da-cunha","tag-fatima","tag-heliopolis","tag-infeccao","tag-itapicuru","tag-jeremoabo","tag-morte","tag-noticias","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-saude","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=28359"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28359\/revisions"}],"predecessor-version":[{"id":28360,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28359\/revisions\/28360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/24830"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=28359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=28359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=28359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}