{"id":28916,"date":"2020-08-28T14:38:19","date_gmt":"2020-08-28T17:38:19","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=28916"},"modified":"2020-08-28T14:38:19","modified_gmt":"2020-08-28T17:38:19","slug":"teste-da-unesp-identifica-assintomaticos-de-covid-19-pela-saliva","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2020\/08\/28\/teste-da-unesp-identifica-assintomaticos-de-covid-19-pela-saliva\/","title":{"rendered":"Teste da Unesp identifica assintom\u00e1ticos de covid-19 pela saliva"},"content":{"rendered":"<p style=\"text-align: justify;\">Um teste de rastreamento de covid-19 por meio da saliva humana est\u00e1 sendo incorporada \u00e0 rotina de trabalho do Hospital das Cl\u00ednicas da Faculdade de Medicina de Botucatu (HCFMB), no interior de S\u00e3o Paulo, para evitar surtos da doen\u00e7a no local. O teste ajuda a identificar pacientes assintom\u00e1ticos e, se aplicado de forma peri\u00f3dica, tem potencial para agilizar o retorno seguro \u00e0s atividades presenciais.<!--more--><\/p>\n<p style=\"text-align: justify;\">A nova metodologia, realizada em parceria com a Universidade Estadual Paulista (Unesp), j\u00e1 foi usada por algumas unidades da universidade e est\u00e1 sendo integrada ao plano de retomada das atividades presenciais da Unesp. De acordo com a universidades, o teste de rastreamento est\u00e1 baseado em estudos cient\u00edficos internacionais que apontaram a saliva como material biol\u00f3gico de alta sensibilidade para indicar a presen\u00e7a do novo coronav\u00edrus e atestaram que as gl\u00e2ndulas salivares tamb\u00e9m possuem o receptor para o Sars-CoV-2, v\u00edrus causador da covid-19.<\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-thumbnail wp-image-9394 alignleft\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab-320x240.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab-320x240.jpg 320w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab-195x146.jpg 195w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab-50x38.jpg 50w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab-100x75.jpg 100w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab.jpg 400w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>A partir destes achados cient\u00edficos, publicados em peri\u00f3dicos de alto impacto como a revista The Lancet, uma equipe de professores da Unesp que trabalham no Hospital das Cl\u00ednicas de Botucatu concebeu um teste de rastreamento para pacientes assintom\u00e1ticos chamado por ora de pool de saliva, que consiste em coletar salivas de 8 a 15 pessoas aparentemente saud\u00e1veis, em frascos individuais, para identificar a presen\u00e7a do novo coronav\u00edrus.<\/p>\n<p style=\"text-align: justify;\">O m\u00e9todo de an\u00e1lise das amostras \u00e9 o PCR-RT, j\u00e1 amplamente utilizado. A diferen\u00e7a \u00e9 que o hospital est\u00e1 fazendo o teste atrav\u00e9s da saliva. \u201cO m\u00e9todo de detec\u00e7\u00e3o do coronav\u00edrus \u00e9 o PCR-RT que \u00e9 considerado a melhor escolha para diagn\u00f3stico, quando feito atrav\u00e9s de swab orofar\u00edngeo. Para o rastreamento, estamos fazendo ent\u00e3o o mesmo PCR-RT mas em saliva, atrav\u00e9s de pools de 15 pessoas. Quando o pool \u00e9 negativo, todos s\u00e3o considerados negativos. Se um pool \u00e9 positivo, o exame \u00e9 repetido individualmente nessas 15 pessoas de um pool, e encontrado o indiv\u00edduo positivo. Essa pessoa ser\u00e1 consultada e ser\u00e1 colhido o swab orofar\u00edngeo, que \u00e9 o m\u00e9todo diagn\u00f3stico\u201d, explica a Diretora de Assist\u00eancia do HCFMB, a m\u00e9dica Erika Ortolan.<\/p>\n<p style=\"text-align: justify;\">Na opini\u00e3o da m\u00e9dica, o teste tem potencial para ser comercializado. \u201cCom o uso da saliva, que trouxe possibilidade de realizar em massa, pois \u00e9 uma coleta simples, realizada pela pr\u00f3pria pessoa, e com o processamento em pool, h\u00e1 uma economia de reagentes\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Atividades presenciais<\/strong><\/p>\n<p style=\"text-align: justify;\">A an\u00e1lise \u00e9 feita por grupos, o que amplia a escala da testagem. Se todos derem negativo para o v\u00edrus, as pessoas ficam liberadas para trabalhar at\u00e9 o pr\u00f3ximo teste. Se houver identifica\u00e7\u00e3o do Sars-CoV-2 em algum dos grupos que se submeteram ao teste de rastreamento, todas as salivas daquele grupo passar\u00e3o por teste complementar para descobrir quem est\u00e1 infectado. Identificada a pessoa com a carga viral, ela \u00e9 afastada do trabalho e seus colegas passam a ser alvos de um monitoramento mais rigoroso nos dias seguintes ao resultado.<\/p>\n<p style=\"text-align: justify;\">O teste \u00e9 feito quinzenalmente no hospital, explica a diretora. \u201cNas primeiras cinco semanas desse rastreamento, estamos fazendo quinzenalmente para \u00e1reas covid [em que s\u00e3o tratados pacientes com a doen\u00e7a] e mensalmente para \u00e1reas n\u00e3o covid [outras \u00e1reas do hospital como o administrativo]. Em setembro iniciaremos semanal para \u00e1reas covid e quinzenalmente para \u00e1reas n\u00e3o covid\u201d, detalhou Erika.<\/p>\n<p style=\"text-align: justify;\">A nova metodologia do pool de saliva foi apresentada \u00e0 comunidade cient\u00edfica internacional no m\u00eas passado pela Unesp, durante um webinar sobre estrat\u00e9gias para impedir o surgimento de surtos da covid-19 em hospitais, que contou com a participa\u00e7\u00e3o do professor Carlos Magno Fortaleza, da Faculdade de Medicina da Unesp e da comiss\u00e3o de controle de infec\u00e7\u00e3o hospitalar do Hospital das Cl\u00ednicas de Botucatu.<\/p>\n<p style=\"text-align: justify;\">O teste foi padronizado no Laborat\u00f3rio de Biologia Molecular do Hospital das Cl\u00ednicas da Faculdade de Medicina de Botucatu (HC-FMB-Unesp), sob responsabilidade da professora Rejane Grotto. Os primeiros a realizarem os testes de rastreamento por pool de saliva foram os estudantes de internato da Faculdade de Medicina da Unesp, que est\u00e3o no 5\u00ba ano e 6\u00ba ano da gradua\u00e7\u00e3o e atuam dentro do hospital.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Boc\u00e3o News<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um teste de rastreamento de covid-19 por meio da saliva humana est\u00e1 sendo incorporada \u00e0 rotina de trabalho do Hospital das Cl\u00ednicas da Faculdade de Medicina de Botucatu (HCFMB), no interior de S\u00e3o Paulo, para evitar surtos da doen\u00e7a no local. O teste ajuda a identificar pacientes assintom\u00e1ticos e, se aplicado de forma peri\u00f3dica, tem &hellip;<\/p>\n","protected":false},"author":2,"featured_media":22081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[34,70,69,19],"tags":[100,71,48,49,93,75,45,3429,3486,46,129,1463,107,44,132,230,3828,106,203,120,51,109,88,47,61,111,190,3870],"class_list":["post-28916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaques","category-noticias2","category-saude","tag-adustina","tag-antas","tag-araci","tag-banzae","tag-brasil","tag-cicero-dantas","tag-cipo","tag-coronavirus","tag-covid-19","tag-crisopolis","tag-euclides-da-cunha","tag-exame","tag-fatima","tag-heliopolis","tag-itapicuru","tag-jeremoabo","tag-noticias","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-saude","tag-sitio-do-quinto","tag-tucano","tag-unesp"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=28916"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28916\/revisions"}],"predecessor-version":[{"id":28917,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28916\/revisions\/28917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/22081"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=28916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=28916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=28916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}