{"id":29688,"date":"2020-09-29T09:09:41","date_gmt":"2020-09-29T12:09:41","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=29688"},"modified":"2020-09-29T09:09:41","modified_gmt":"2020-09-29T12:09:41","slug":"ricardo-salles-aprova-extincao-de-normas-que-protegem-manguezal-e-restinga","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2020\/09\/29\/ricardo-salles-aprova-extincao-de-normas-que-protegem-manguezal-e-restinga\/","title":{"rendered":"Ricardo Salles aprova extin\u00e7\u00e3o de normas que protegem manguezal e restinga"},"content":{"rendered":"<p style=\"text-align: justify;\">O ministro do Meio Ambiente, Ricardo Salles, aprovou nesta segunda-feira (28) a extin\u00e7\u00e3o de instrumentos de prote\u00e7\u00e3o dos mangues e das restingas, faixas de vegeta\u00e7\u00e3o comumente encontradas no litoral do Nordeste, por meio da revoga\u00e7\u00e3o das resolu\u00e7\u00f5es 302 e 303 do Conselho Nacional do Meio Ambiente (Conama).\u00a0<!--more--><\/p>\n<p style=\"text-align: justify;\">A revoga\u00e7\u00e3o dessas regras abre espa\u00e7o para especula\u00e7\u00e3o imobili\u00e1ria nas faixas de vegeta\u00e7\u00e3o das praias e ocupa\u00e7\u00e3o de \u00e1reas de mangues para produ\u00e7\u00e3o de camar\u00e3o.<\/p>\n<div data-mvc-banner=\"leaderboard\"><\/div>\n<p><script type=\"text\/javascript\"> (function(storeName) { var b = document.createElement('script'); b.type = 'text\/javascript'; b.async = true; b.src = 'https:\/\/www.magazinevoce.com.br\/js\/banner.js?store='+ storeName; var s = document.getElementsByTagName('script')[0]; s.parentNode.insertBefore(b, s); })('Nvscosta'); <\/script><\/p>\n<p style=\"text-align: justify;\">O Conama revogou ainda uma resolu\u00e7\u00e3o que exigia o licenciamento ambiental para projetos de irriga\u00e7\u00e3o, al\u00e9m de aprovar uma nova regra, substituindo as normas que determinavam o descarte ambiental apropriado de materiais de embalagens e restos de agrot\u00f3xicos, para que possam ser queimados em fornos industriais e transformados em cimento.<\/p>\n<p style=\"text-align: justify;\">O Conama, presidido por Salles, \u00e9 controlado majoritariamente por minist\u00e9rios e membros do governo federal. Durante a lideran\u00e7a do ministro, estados e entidades civis perderam representa\u00e7\u00e3o. O \u00f3rg\u00e3o teve seus membros reduzidos de 96 para 23 representantes.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Metro1<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro do Meio Ambiente, Ricardo Salles, aprovou nesta segunda-feira (28) a extin\u00e7\u00e3o de instrumentos de prote\u00e7\u00e3o dos mangues e das restingas, faixas de vegeta\u00e7\u00e3o comumente encontradas no litoral do Nordeste, por meio da revoga\u00e7\u00e3o das resolu\u00e7\u00f5es 302 e 303 do Conselho Nacional do Meio Ambiente (Conama).\u00a0<\/p>\n","protected":false},"author":2,"featured_media":26653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[34,70,69,21],"tags":[100,71,48,49,93,75,45,46,129,107,44,132,230,3924,3750,3776,3828,106,203,120,51,109,88,47,3777,111,190],"class_list":["post-29688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaques","category-noticias2","category-politica","tag-adustina","tag-antas","tag-araci","tag-banzae","tag-brasil","tag-cicero-dantas","tag-cipo","tag-crisopolis","tag-euclides-da-cunha","tag-fatima","tag-heliopolis","tag-itapicuru","tag-jeremoabo","tag-mangues","tag-meio-ambiente","tag-ministerio-do-meio-ambiente","tag-noticias","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-ricardo-salles","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=29688"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29688\/revisions"}],"predecessor-version":[{"id":29689,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29688\/revisions\/29689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/26653"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=29688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=29688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=29688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}