{"id":29693,"date":"2020-09-29T12:01:35","date_gmt":"2020-09-29T15:01:35","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=29693"},"modified":"2020-09-29T22:48:56","modified_gmt":"2020-09-30T01:48:56","slug":"ministerio-publico-denuncia-flavio-bolsonaro-e-queiroz-por-rachadinha-na-alerj","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2020\/09\/29\/ministerio-publico-denuncia-flavio-bolsonaro-e-queiroz-por-rachadinha-na-alerj\/","title":{"rendered":"Minist\u00e9rio P\u00fablico denuncia Fl\u00e1vio Bolsonaro e Queiroz por &#8216;rachadinha&#8217; na Alerj"},"content":{"rendered":"<p style=\"text-align: justify;\">Depois de mais de dois anos de investiga\u00e7\u00e3o, o Minist\u00e9rio P\u00fablico do Rio (MP-RJ) denunciou ao Tribunal de Justi\u00e7a do Rio o\u00a0senador Fl\u00e1vio Bolsonaro\u00a0(Republicanos-RJ) e\u00a0Fabr\u00edcio Queiroz, subtenente da reserva da Pol\u00edcia Militar e assessor do senador no per\u00edodo em que foi deputado estadual no Rio.<!--more--><\/p>\n<p style=\"text-align: justify;\">Fl\u00e1vio foi apontado como l\u00edder da organiza\u00e7\u00e3o criminosa, e Queiroz, como o operador do esquema de corrup\u00e7\u00e3o que funcionava no antigo gabinete na Assembleia Legislativa. Ambos foram acusados pelos crimes de peculato, lavagem de dinheiro e organiza\u00e7\u00e3o criminosa.<\/p>\n<p style=\"text-align: justify;\">A partir dos dados das quebras de sigilo banc\u00e1rio e fiscal, os promotores apontam que o senador usou, pelo menos, R$ 2,7 milh\u00f5es em dinheiro vivo do esquema das rachadinhas. Os valores somam os tr\u00eas m\u00e9todos pelo qual o filho do\u00a0presidente Jair Bolsonaro\u00a0&#8220;lavou&#8221; o dinheiro em esp\u00e9cie.<\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-thumbnail wp-image-4869 aligncenter\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-720x181.jpg\" alt=\"\" width=\"720\" height=\"181\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre.jpg 720w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-260x65.jpg 260w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-50x13.jpg 50w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-150x38.jpg 150w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>Em junho, Queiroz foi preso na casa do\u00a0advogado Frederick Wassef, em Atibaia, no interior de S\u00e3o Paulo. Wassef era advogado de Fl\u00e1vio na investiga\u00e7\u00e3o at\u00e9 aquele momento. Ele foi trazido ao Rio para cumprir a pris\u00e3o em Bangu, mas um habeas corpus do ministro Gilmar Mendes, do\u00a0Supremo Tribunal Federal (STF), permitiu que ele fosse para pris\u00e3o domiciliar em seu apartamento na Taquara, na Zona Oeste do Rio.<\/p>\n<p style=\"text-align: justify;\"><strong>A INVESTIGA\u00c7\u00c3O<\/strong><\/p>\n<p style=\"text-align: justify;\">A investiga\u00e7\u00e3o do MP-RJ teve in\u00edcio em julho de 2018, depois que um relat\u00f3rio do Conselho de Controle de Atividades Financeiras (Coaf) identificou a movimenta\u00e7\u00e3o at\u00edpica de R$ 1,2 milh\u00e3o na conta de Queiroz. Al\u00e9m disso, foi apontado\u00a0no documento\u00a0que oito assessores de Fl\u00e1vio faziam repasses para Queiroz,\u00a0al\u00e9mde estar\u00a0assinalada a participa\u00e7\u00e3o de integrantes da\u00a0fam\u00edlia\u00a0do ex-assessor. Foram identificadas transfer\u00eancias e dep\u00f3sitos de M\u00e1rcia Aguiar, Nath\u00e1lia e Evelyn Queiroz, mulher e filhas do subtenente.<\/p>\n<p style=\"text-align: justify;\">Quando o MP-RJ avan\u00e7ou nas investiga\u00e7\u00f5es, ap\u00f3s a quebra de sigilo banc\u00e1rio e fiscal de 106 pessoas e empresas em abril de 2019, verificou provas de um esquema no qual assessores eram nomeados e tinham que devolver a maior parte de seus sal\u00e1rios para Fabr\u00edcio Queiroz. Muitos, inclusive, n\u00e3o atuavam efetivamente e eram &#8220;funcion\u00e1rios fantasmas&#8221;. O dinheiro era repassado por transfer\u00eancias, dep\u00f3sitos, mas tamb\u00e9m em esp\u00e9cie. Depois, segundo a investiga\u00e7\u00e3o, o dinheiro era lavado e voltava para Fl\u00e1vio por meio de transa\u00e7\u00f5es imobili\u00e1rias, na loja de chocolates e tamb\u00e9m no pagamento de despesas pessoais com dinheiro vivo, o que oculta a origem.<\/p>\n<p style=\"text-align: justify;\">S\u00e3o 23 os ex-assessores citados em relat\u00f3rios do Grupo de Atua\u00e7\u00e3o Especializada no Combate \u00e0 Corrup\u00e7\u00e3o (Gaecc) do MP-RJ. Eles s\u00e3o divididos em tr\u00eas grupos. O primeiro, composto por 13 ex-funcion\u00e1rios, \u00e9 o n\u00facleo ligado a Queiroz, formado por seus familiares, al\u00e9m de vizinhos e amigos indicados por ele para o gabinete. Esses 13 ex-assessores depositaram, ao longo dos 11 anos, R$ 2,06 milh\u00f5es na conta banc\u00e1ria de Queiroz (69% do valor em dinheiro vivo). Al\u00e9m disso, esse grupo sacou R$ 2,9 milh\u00f5es em esp\u00e9cie ao longo desse per\u00edodo.<\/p>\n<p style=\"text-align: justify;\">No segundo grupo, constam ainda\u00a0Danielle N\u00f3brega e Raimunda Veras Magalh\u00e3es, ex-mulher e m\u00e3e de Adriano N\u00f3brega, ex-capit\u00e3o do Bope e l\u00edder de uma mil\u00edcia de Rio das Pedras, que foi morto em fevereiro. Elas repassaram juntas para Queiroz um total de R$ 200 mil. J\u00e1 as pizzarias de Raimunda ainda repassaram outros R$ 200 mil para Queiroz.<\/p>\n<p style=\"text-align: justify;\">O terceiro grupo descrito pelo MP cont\u00e9m dez\u00a0ex-assessores\u00a0residentes em Resende, a cidade onde membros da fam\u00edlia Bolsonaro viveram, no Sul fluminense. Nove deles t\u00eam parentesco com\u00a0Ana Cristina Siqueira Valle, ex-mulher e m\u00e3e do filho mais novo do presidente Jair Bolsonaro. Dos dez ex-funcion\u00e1rios do n\u00facleo de Resende, seis sacaram em esp\u00e9cie mais de 90% dos sal\u00e1rios recebidos, e outros tr\u00eas acima de 70%. Foi um total de R$ 4 milh\u00f5es.<\/p>\n<p style=\"text-align: justify;\">O MP-RJ tamb\u00e9m aponta que alguns esses funcion\u00e1rios n\u00e3o davam expediente, de fato, no gabinete de Fl\u00e1vio ou atuavam como assessores. Nos autos, os promotores citaram reportagem do GLOBO, de junho do ano passado, que apontou quatro dessas pessoas que constaram como funcion\u00e1rios, mas nunca exerceram os cargos de fato na Alerj.<\/p>\n<p style=\"text-align: justify;\">Francisco Siqueira Diniz, cursava faculdade em tempo integral em Barra Mansa, e jamais teve crach\u00e1 da Alerj. Tamb\u00e9m \u00e9 apontada a situa\u00e7\u00e3o de Andrea Siqueira Valle, fisiculturista, que constou como assessora de Fl\u00e1vio por dez anos. Os aposentados Jos\u00e9 Proc\u00f3pio Valle e Maria Jos\u00e9 Siqueira Silva, que sempre moraram em Resende, tamb\u00e9m foram apontados.<\/p>\n<p style=\"text-align: justify;\">Ao todo, os promotores apontam nos autos, seis grupos da organiza\u00e7\u00e3o criminosa. Al\u00e9m dos assessores, outros tr\u00eas grupos mencionam os envolvidos na lavagem de dinheiro: o n\u00facleo com Alexandre Santini, s\u00f3cio de Fl\u00e1vio na loja de chocolates, outro com Glenn Dillard e sua empresa Linear Enterprises Consultoria Imobili\u00e1ria e um \u00faltimo com o policial militar Diego Ambr\u00f3sio e sua empresa de vigil\u00e2ncia, Santa Clara<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: Yahoo Not\u00edcias<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de mais de dois anos de investiga\u00e7\u00e3o, o Minist\u00e9rio P\u00fablico do Rio (MP-RJ) denunciou ao Tribunal de Justi\u00e7a do Rio o\u00a0senador Fl\u00e1vio Bolsonaro\u00a0(Republicanos-RJ) e\u00a0Fabr\u00edcio Queiroz, subtenente da reserva da Pol\u00edcia Militar e assessor do senador no per\u00edodo em que foi deputado estadual no Rio.<\/p>\n","protected":false},"author":2,"featured_media":20521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[34,70,69,21],"tags":[100,1820,71,48,49,93,75,45,46,129,2031,107,1976,44,132,230,3828,106,203,120,51,109,3282,88,47,300,111,190],"class_list":["post-29693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaques","category-noticias2","category-politica","tag-adustina","tag-alerj","tag-antas","tag-araci","tag-banzae","tag-brasil","tag-cicero-dantas","tag-cipo","tag-crisopolis","tag-euclides-da-cunha","tag-fabricio-queiroz","tag-fatima","tag-flavio-bolsonaro","tag-heliopolis","tag-itapicuru","tag-jeremoabo","tag-noticias","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-rachadinha","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-rio-de-janeiro","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=29693"}],"version-history":[{"count":2,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29693\/revisions"}],"predecessor-version":[{"id":29713,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29693\/revisions\/29713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/20521"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=29693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=29693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=29693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}