{"id":29710,"date":"2020-09-29T23:09:10","date_gmt":"2020-09-30T02:09:10","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=29710"},"modified":"2020-09-29T23:09:10","modified_gmt":"2020-09-30T02:09:10","slug":"laudo-atesta-que-a-agua-distribuida-pela-embasa-em-localidades-de-araci-ba-e-segura-para-consumo","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2020\/09\/29\/laudo-atesta-que-a-agua-distribuida-pela-embasa-em-localidades-de-araci-ba-e-segura-para-consumo\/","title":{"rendered":"Laudo atesta que a \u00e1gua distribu\u00edda pela Embasa em localidades de Araci-BA \u00e9 segura para consumo"},"content":{"rendered":"<p style=\"text-align: justify;\">O laudo com o resultado de an\u00e1lise ampla de par\u00e2metros de potabilidade realizada pelo Laborat\u00f3rio Central da Embasa em amostras de \u00e1gua coletadas no dia 16 de setembro, na sa\u00edda do po\u00e7o (manancial), na unidade de tratamento e na rede distribuidora de \u00e1gua que atende Lagoa do Boi, Lagoa dos Cavalos e Jurema, no munic\u00edpio de Araci, atesta que a \u00e1gua distribu\u00edda pela Embasa nessas localidades est\u00e1 em conformidade com os par\u00e2metros de potabilidade exigidos pelo Minist\u00e9rio da Sa\u00fade, diz a nota da Embasa enviada \u00e0 reda\u00e7\u00e3o da Voz do Campo.\u00a0<!--more--><\/p>\n<p style=\"text-align: justify;\">De acordo com a empresa, o trabalho de coleta realizado pela Embasa, no dia 16, tamb\u00e9m contemplou os a\u00e7udes existentes em Lagoa do Boi e Lagoa dos Cavalos, fonte alternativa utilizada por parte da popula\u00e7\u00e3o. A an\u00e1lise das amostras de \u00e1gua bruta coletada nesses a\u00e7udes mostrou valores elevados para Coliformes Totais e Escherichia Coli, indicando risco em termos microbiol\u00f3gicos para consumo direto da \u00e1gua desses mananciais sem tratamento pr\u00e9vio. Al\u00e9m desses par\u00e2metros, Alum\u00ednio Total, Ferro Total e Mangan\u00eas tamb\u00e9m apresentaram valores alterados em rela\u00e7\u00e3o ao que determina o Minist\u00e9rio da Sa\u00fade para \u00e1gua pot\u00e1vel.<\/p>\n<p style=\"text-align: justify;\"><strong>Cont\u00e1gio por Rotav\u00edrus \u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-thumbnail wp-image-9394 alignleft\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab-320x240.jpg\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab-320x240.jpg 320w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab-195x146.jpg 195w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab-50x38.jpg 50w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab-100x75.jpg 100w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/07\/05elab.jpg 400w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>Diante do an\u00fancio da Secretaria de Sa\u00fade de Araci do cont\u00e1gio por Rotav\u00edrus pelas pessoas que apresentaram sintomas seguidos de hospitaliza\u00e7\u00e3o, entre os dias 9 e 11 de setembro, os resultados de qualidade da \u00e1gua apresentados pelo laborat\u00f3rio da Embasa confirmam a seguran\u00e7a da \u00e1gua distribu\u00edda pela empresa, pois, de acordo com a Organiza\u00e7\u00e3o Mundial de Sa\u00fade, o Rotav\u00edrus n\u00e3o sobrevive por mais de 30 minutos em \u00e1gua com teor de cloro de 1mg\/litro e a \u00e1gua distribu\u00edda pela Embasa apresenta teor de cloro superior a 1mg\/litro, al\u00e9m de passar mais de 30 minutos no sistema, entre a unidade de tratamento e o reservat\u00f3rio de distribui\u00e7\u00e3o, at\u00e9 chegar \u00e0 casa dos usu\u00e1rios. Para o superintendente de Opera\u00e7\u00e3o da Regi\u00e3o Norte, Raimundo Neto, o resultado das an\u00e1lises descartam a hip\u00f3tese da \u00e1gua distribu\u00edda pela Embasa ser um vetor de cont\u00e1gio. \u201cA Embasa vai continuar apoiando, no que puder, as vigil\u00e2ncias sanit\u00e1rias do Munic\u00edpio e do Estado na investiga\u00e7\u00e3o sobre as causas do cont\u00e1gio por Rotav\u00edrus no munic\u00edpio e, ap\u00f3s oficializar a entrega dos laudos ao poder p\u00fablico e obter os resultados do Lacen, vai iniciar o processo de retomada do abastecimento de \u00e1gua tratada nessas localidades, pois \u00e9 uma garantia de sa\u00fade para a popula\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><strong>Par\u00e2metros analisados\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">Os par\u00e2metros que constam no laudo formam o padr\u00e3o microbiol\u00f3gico, padr\u00e3o de subst\u00e2ncias qu\u00edmicas que representam risco \u00e0 sa\u00fade, padr\u00e3o de cianotoxinas e padr\u00e3o organol\u00e9ptico (cor, entre outros) definidos pelo Minist\u00e9rio da Sa\u00fade no Anexo XX da Portaria de Consolida\u00e7\u00e3o No. 05\/2017.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: A Voz do Campo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O laudo com o resultado de an\u00e1lise ampla de par\u00e2metros de potabilidade realizada pelo Laborat\u00f3rio Central da Embasa em amostras de \u00e1gua coletadas no dia 16 de setembro, na sa\u00edda do po\u00e7o (manancial), na unidade de tratamento e na rede distribuidora de \u00e1gua que atende Lagoa do Boi, Lagoa dos Cavalos e Jurema, no munic\u00edpio &hellip;<\/p>\n","protected":false},"author":2,"featured_media":29711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[41,70,69,32,19],"tags":[100,2605,71,48,49,75,45,46,275,129,107,44,132,230,3828,106,203,120,51,109,88,47,3906,111,190],"class_list":["post-29710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-araci","category-destaques","category-noticias2","category-regiao","category-saude","tag-adustina","tag-agua","tag-antas","tag-araci","tag-banzae","tag-cicero-dantas","tag-cipo","tag-crisopolis","tag-embasa","tag-euclides-da-cunha","tag-fatima","tag-heliopolis","tag-itapicuru","tag-jeremoabo","tag-noticias","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-rotavirus","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=29710"}],"version-history":[{"count":2,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29710\/revisions"}],"predecessor-version":[{"id":29722,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29710\/revisions\/29722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/29711"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=29710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=29710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=29710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}