{"id":31233,"date":"2020-12-11T21:11:35","date_gmt":"2020-12-12T00:11:35","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=31233"},"modified":"2020-12-11T21:11:35","modified_gmt":"2020-12-12T00:11:35","slug":"policia-do-rs-indicia-seis-pela-morte-de-joao-alberto-em-supermercado","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2020\/12\/11\/policia-do-rs-indicia-seis-pela-morte-de-joao-alberto-em-supermercado\/","title":{"rendered":"Pol\u00edcia do RS indicia seis pela morte de Jo\u00e3o Alberto em supermercado"},"content":{"rendered":"<p style=\"text-align: justify;\">A Pol\u00edcia Civil do Rio Grande do Sul afirmou, na manh\u00e3 desta sexta-feira (11), que indiciou seis pessoas por homic\u00eddio triplamente qualificado no caso de\u00a0<a href=\"https:\/\/www.portalalerta.com.br\/index.php\/2020\/11\/20\/no-dia-da-consciencia-negra-a-carne-mais-barata-do-carrefour-e-a-negra\/\"><strong>Jo\u00e3o Alberto Silveira Freitas, espancado e morto por seguran\u00e7as\u00a0<\/strong><\/a>do supermercado Carrefour, no dia 19 de novembro, v\u00e9spera da Consci\u00eancia Negra.<!--more--><\/p>\n<p style=\"text-align: justify;\">A Pol\u00edcia do Rio Grande do Sul finalizou e entregou o inqu\u00e9rito sobre o caso na manh\u00e3 desta sexta-feira. O laudo, que ser\u00e1 remetido \u00e0 an\u00e1lise judicial, aponta que o motivo da morte de Jo\u00e3o Alberto foi asfixia mec\u00e2nica. Ele morreu ao ser escapando pelos seguran\u00e7as do hipermercado. As investiga\u00e7\u00f5es apontam ainda que um dos vigilantes teria impedido a chegada do SAMU para socorrer o homem.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m dos dois vigilantes e a fiscal da loja que estavam presos desde o dia do crime, outros tr\u00eas funcion\u00e1rios foram indiciados por homic\u00eddio triplamente qualificado por motivo torpe, emprego de recurso que dificultou a defesa da v\u00edtima e asfixia por meio de sufoca\u00e7\u00e3o indireta.<\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-thumbnail wp-image-4869 aligncenter\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-720x181.jpg\" alt=\"\" width=\"720\" height=\"181\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre.jpg 720w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-260x65.jpg 260w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-50x13.jpg 50w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2018\/02\/Auto-Escola-Nobre-150x38.jpg 150w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>Segundo a pol\u00edcia os novos indiciados s\u00e3o Rafael Rezende, Cleiton Silva Santos e\u00a0 Paulo Francisco da Silva, os tr\u00eas trabalhavam como seguran\u00e7as do supermercado e podem ir a j\u00fari popular.<\/p>\n<p style=\"text-align: justify;\">A pol\u00edcia afirmou ainda que embora n\u00e3o tenha encontrado provas t\u00e9cnicas de que os suspeitos tenham proferido palavras racistas a Jo\u00e3o Albeto a cor da pele e a condi\u00e7\u00e3o social n\u00e3o foi desconsiderada na investiga\u00e7\u00e3o em func\u00e3o do racismo estrutural.<\/p>\n<p style=\"text-align: justify;\">Em depoimento, nenhum dos indiciados soube dizer qual o comportamento e as supostas palavras agressivas que teriam sido ditas por Jo\u00e3o Alberto a uma funcion\u00e1ria, o que indica a motiva\u00e7\u00e3o preconceituosa do crime.<\/p>\n<p style=\"text-align: justify;\">Os tr\u00eas novos indiciados permanecessem soltos enquanto a Justi\u00e7a do Rio Grande do Sul decide se eles v\u00e3o responder em liberdade ou presos preventivamente.<\/p>\n<p style=\"text-align: justify;\"><em>Fonte: R7<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil do Rio Grande do Sul afirmou, na manh\u00e3 desta sexta-feira (11), que indiciou seis pessoas por homic\u00eddio triplamente qualificado no caso de\u00a0Jo\u00e3o Alberto Silveira Freitas, espancado e morto por seguran\u00e7as\u00a0do supermercado Carrefour, no dia 19 de novembro, v\u00e9spera da Consci\u00eancia Negra.<\/p>\n","protected":false},"author":2,"featured_media":30725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[34,70,69,22],"tags":[100,73,71,48,49,93,4003,75,45,46,129,107,44,206,2712,132,230,169,3828,106,203,120,51,122,109,88,47,1858,111,190],"class_list":["post-31233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaques","category-noticias2","category-seguranca","tag-adustina","tag-agressao","tag-antas","tag-araci","tag-banzae","tag-brasil","tag-carrefour","tag-cicero-dantas","tag-cipo","tag-crisopolis","tag-euclides-da-cunha","tag-fatima","tag-heliopolis","tag-homicidio","tag-indiciados","tag-itapicuru","tag-jeremoabo","tag-morte","tag-noticias","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-policia-civil","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-segurancas","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=31233"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31233\/revisions"}],"predecessor-version":[{"id":31234,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31233\/revisions\/31234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/30725"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=31233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=31233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=31233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}