{"id":34740,"date":"2021-04-28T16:03:00","date_gmt":"2021-04-28T19:03:00","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=34740"},"modified":"2021-04-28T15:19:31","modified_gmt":"2021-04-28T18:19:31","slug":"acao-contra-o-trafico-de-drogas-termina-com-acidente-um-morto-e-dois-presos-em-cipo-ba","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2021\/04\/28\/acao-contra-o-trafico-de-drogas-termina-com-acidente-um-morto-e-dois-presos-em-cipo-ba\/","title":{"rendered":"A\u00e7\u00e3o contra o tr\u00e1fico de drogas, termina com acidente, um morto e dois presos, em Cip\u00f3-BA"},"content":{"rendered":"\n<p>A madrugada desta quarta-feira (28) foi bastante movimentada em Cip\u00f3-BA. Por volta de 00:15h, policiais militares da 21\u00aa CIPM em a\u00e7\u00e3o conjunta com a CIPE Nordeste, montaram uma estrat\u00e9gia para impedir a pr\u00e1tica de tr\u00e1fico de drogas na cidade, mediante informa\u00e7\u00f5es obtidas por equipes da intelig\u00eancia policial.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Os militares flagraram o momento em que um ve\u00edculo Fiat Uno AYN 3941, com licen\u00e7a de S\u00e3o Paulo entrou na Rua do Jorro, bairro 13 maio, e que numa resid\u00eancia, os ocupantes do ve\u00edculo, realizaram a entrega de um pacote a um rapaz que se encontrava em frente ao local. Com a aproxima\u00e7\u00e3o policial, o condutor do carro deu in\u00edcio a uma fuga, sendo acompanhado a todo momento pelos policiais.<\/p>\n\n\n\n<p>Foram realizados diversos cercos pelas ruas da cidade, sendo que numa dessas a\u00e7\u00f5es, o suspeito rompeu o bloqueio, passando a efetuar disparos de arma de fogo, contra os policiais, que revidaram. Na sequ\u00eancia, o motorista perdeu o controle da dire\u00e7\u00e3o, chocando o carro contra a porta de um estabelecimento comercial. No ve\u00edculo foi encontrado um casal, identificado como Samuel Oliveira Veras de Souza, 42 anos, e Andreia Leite Gouveia (Coroa), 39 anos, ambos feridos, sendo o homem baleado, &nbsp;e a mulher devido ao acidente. O casal foi socorrido para o Hospital Municipal da cidade, onde Samuel n\u00e3o resistiu e evoluiu a \u00f3bito, enquanto Andreia foi transferida para o Hospital Geral Santa Tereza, em Ribeira do Pombal-BA, onde se encontra custodiada.<\/p>\n\n\n\n<div data-mvc-banner=\"leaderboard\"><\/div><script type=\"text\/javascript\"> (function(storeName) { var b = document.createElement('script'); b.type = 'text\/javascript'; b.async = true; b.src = 'https:\/\/www.magazinevoce.com.br\/js\/banner.js?store='+ storeName; var s = document.getElementsByTagName('script')[0]; s.parentNode.insertBefore(b, s); })('Nvscosta'); <\/script>\n\n\n\n<p>Na sequ\u00eancia os policiais seguiram para o local onde foi iniciada a dilig\u00eancia, sendo poss\u00edvel encontrar mais material il\u00edcito, bem como prenderam Eduardo de Jesus Santos (Dudu), 42 anos, que foi conduzido e apresentado na Delegacia de Pol\u00edcia Civil local, juntamente com todo material apreendido, para a devida lavratura da ocorr\u00eancia.<\/p>\n\n\n\n<p>Foram apreendidos: dois rev\u00f3lveres cal. 32, sendo um com seis muni\u00e7\u00f5es intactas, e o outro com seis muni\u00e7\u00f5es, tr\u00eas delas deflagradas e tr\u00eas intactas; 01 espingarda de ca\u00e7a; 01 tablete de coca\u00edna prensada; 03 po\u00e7\u00f5es de coca\u00edna; 03 po\u00e7\u00f5es de maconha; 04 pedras de crack; R$ 709,00 em esp\u00e9cie; 02 aparelhos celulares; e o carro utilizado para o cometimento do crime.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"1024\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2021\/04\/confronto-em-Cipo-2021.1-640x1024.jpeg\" alt=\"\" class=\"wp-image-34750\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2021\/04\/confronto-em-Cipo-2021.1-640x1024.jpeg 640w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2021\/04\/confronto-em-Cipo-2021.1-150x240.jpeg 150w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2021\/04\/confronto-em-Cipo-2021.1-768x1229.jpeg 768w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2021\/04\/confronto-em-Cipo-2021.1-91x146.jpeg 91w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2021\/04\/confronto-em-Cipo-2021.1-31x50.jpeg 31w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2021\/04\/confronto-em-Cipo-2021.1-47x75.jpeg 47w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2021\/04\/confronto-em-Cipo-2021.1.jpeg 800w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption>Material apreendido em posse dos criminosos <\/figcaption><\/figure>\n\n\n\n<p><em>Reda\u00e7\u00e3o: Portal Alerta<\/em><\/p>\n\n\n\n<p><strong><em>#fiqueemcasa<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>#usemascaras<\/em><\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A madrugada desta quarta-feira (28) foi bastante movimentada em Cip\u00f3-BA. Por volta de 00:15h, policiais militares da 21\u00aa CIPM em a\u00e7\u00e3o conjunta com a CIPE Nordeste, montaram uma estrat\u00e9gia para impedir a pr\u00e1tica de tr\u00e1fico de drogas na cidade, mediante informa\u00e7\u00f5es obtidas por equipes da intelig\u00eancia policial.<\/p>\n","protected":false},"author":2,"featured_media":34751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[13,70,69,32,22],"tags":[4178,178,90,137,169,110,76],"class_list":["post-34740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cipo","category-destaques","category-noticias2","category-regiao","category-seguranca","tag-cipo-2","tag-confronto","tag-ferida","tag-fuga","tag-morte","tag-presos","tag-trafico-de-drogas"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=34740"}],"version-history":[{"count":2,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34740\/revisions"}],"predecessor-version":[{"id":34752,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34740\/revisions\/34752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/34751"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=34740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=34740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=34740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}