{"id":54089,"date":"2024-01-31T15:07:41","date_gmt":"2024-01-31T18:07:41","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=54089"},"modified":"2024-01-31T15:45:18","modified_gmt":"2024-01-31T18:45:18","slug":"jovem-que-morreu-em-encontro-com-jogador-do-corinthians-tinha-corte-de-5-cm-na-regiao-genital","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2024\/01\/31\/jovem-que-morreu-em-encontro-com-jogador-do-corinthians-tinha-corte-de-5-cm-na-regiao-genital\/","title":{"rendered":"Jovem que morreu em encontro com jogador do Corinthians tinha corte de 5 cm na regi\u00e3o genital"},"content":{"rendered":"\n<p>Informa\u00e7\u00e3o foi dada por um m\u00e9dico ao pai da garota; ela teve quatro paradas cardiorrespirat\u00f3rias por conta de hemorragia. |NOVO DIA<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>A jovem de 19 anos que\u00a0morreu durante um encontro com o jogador Dimas C\u00e2ndido de Oliveira Filho, do sub-20 do Corinthians, tinha um corte de cerca de 5 cent\u00edmetros na regi\u00e3o genital. A informa\u00e7\u00e3o foi dada pelo pai dela, que conversou com o m\u00e9dico que atendeu a garota no Hospital Municipal do Tatuap\u00e9 na noite da \u00faltima ter\u00e7a-feira (30).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2023\/01\/Auto-Escola-Sonho.jpg\" alt=\"\" class=\"wp-image-47083\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2023\/01\/Auto-Escola-Sonho.jpg 400w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2023\/01\/Auto-Escola-Sonho-320x240.jpg 320w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n<p>Segundo o registro da ocorr\u00eancia, o m\u00e9dico informou aos policiais que n\u00e3o era poss\u00edvel dizer o que teria causado a lacera\u00e7\u00e3o, e que por isso solicitou que o corpo fosse encaminhado ao Instituto M\u00e9dico Legal (IML) para per\u00edcia.<\/p>\n\n\n\n<p>Em depoimento na delegacia,\u00a0Dimas, que tem 18 anos, afirmou que conheceu a garota pelas redes sociais e que eles marcaram um encontro no apartamento dele, na zona leste de S\u00e3o Paulo. Segundo ele, foi a primeira vez que se viram.<\/p>\n\n\n\n<p>O atleta afirmou que eles n\u00e3o beberam e nem consumiram nenhum entorpecente e que, durante o ato sexual, a jovem teria desmaiado. Ele teria visto sangue na regi\u00e3o \u00edntima dela e acionou o Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu), que orientou que ele realizasse massagem card\u00edaca na garota at\u00e9 a chegada da ambul\u00e2ncia.<\/p>\n\n\n\n<p>Ap\u00f3s isso, Dimas foi junto com o resgate at\u00e9 o hospital e os familiares da jovem foram avisados por uma enfermeira do Samu de que precisavam ir at\u00e9 o local.<\/p>\n\n\n\n<p>No hospital, os m\u00e9dicos disseram \u00e0 fam\u00edlia que a mo\u00e7a tinha sofrido tr\u00eas paradas cardiorrespirat\u00f3rias e que havia perdido muito sangue, mas que tinham conseguido estabilizar seu quatro e estancar o corte. Por\u00e9m, algum tempo depois, ela sofreu mais uma parada, que a levou a \u00f3bito.<\/p>\n\n\n\n<p>O pai da garota afirma que conversou com o m\u00e9dico, que n\u00e3o soube informar se o corte que ela tinha na vagina teria sido provocado pelo atrito do ato sexual ou por algum objeto.<\/p>\n\n\n\n<p>Conforme a Pol\u00edcia Civil, no quarto de Dimas, onde teria ocorrido a rela\u00e7\u00e3o sexual, havia uma pequena quantidade de sangue em cima do colch\u00e3o e no ch\u00e3o, uma camisinha usada e dois cigarros eletr\u00f4nicos.<\/p>\n\n\n\n<p>Segundo a delegacia, foi solicitada a realiza\u00e7\u00e3o de per\u00edcia no apartamento do jogador, a remo\u00e7\u00e3o do corpo para o IML e a realiza\u00e7\u00e3o de exames necrosc\u00f3pico, toxicol\u00f3gico e sexol\u00f3gico.<\/p>\n\n\n\n<p>Em nota, o Sport Club Corinthians Paulista afirmou que est\u00e1 ciente dos acontecimentos, que aguarda a investiga\u00e7\u00e3o dos fatos e que est\u00e1 \u00e0 disposi\u00e7\u00e3o para colaborar com as autoridades e as fam\u00edlias.<\/p>\n\n\n\n<p><em>Fonte: CNN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informa\u00e7\u00e3o foi dada por um m\u00e9dico ao pai da garota; ela teve quatro paradas cardiorrespirat\u00f3rias por conta de hemorragia. |NOVO DIA<\/p>\n","protected":false},"author":2,"featured_media":54087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[34,70,2,69,22],"tags":[100,71,48,495,93,75,4178,4180,129,107,4181,132,230,169,106,203,120,51,122,109,88,47,404,111,6674,190],"class_list":["post-54089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaques","category-esportes","category-noticias2","category-seguranca","tag-adustina","tag-antas","tag-araci","tag-atleta","tag-brasil","tag-cicero-dantas","tag-cipo-2","tag-crisopolis-2","tag-euclides-da-cunha","tag-fatima","tag-heliopolis-2","tag-itapicuru","tag-jeremoabo","tag-morte","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-policia-civil","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-sao-paulo","tag-sitio-do-quinto","tag-sport-clube-corinthians-paulista","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=54089"}],"version-history":[{"count":3,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54089\/revisions"}],"predecessor-version":[{"id":54095,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/54089\/revisions\/54095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/54087"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=54089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=54089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=54089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}