{"id":55870,"date":"2024-04-16T18:08:17","date_gmt":"2024-04-16T21:08:17","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=55870"},"modified":"2024-04-16T18:08:18","modified_gmt":"2024-04-16T21:08:18","slug":"ajudante-de-pedreiro-e-assassinado-a-tiros-enquanto-trabalhava-em-itapicuru-ba","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2024\/04\/16\/ajudante-de-pedreiro-e-assassinado-a-tiros-enquanto-trabalhava-em-itapicuru-ba\/","title":{"rendered":"Ajudante de pedreiro \u00e9 assassinado a tiros enquanto trabalhava em Itapicuru-BA"},"content":{"rendered":"\n<p>Um ajudante de pedreiro foi assassinado a tiros enquanto trabalhava em uma obra, nesta ter\u00e7a-feira (16), no distrito da Lagoa Redonda, em Itapicuru-BA, na divisa com a cidade de Tobias Barreto-SE. At\u00e9 o momento da publica\u00e7\u00e3o desta reportagem, ningu\u00e9m havia sido preso.<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-1024x1024.jpg\" alt=\"\" class=\"wp-image-55693\" width=\"435\" height=\"435\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-1024x1024.jpg 1024w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-240x240.jpg 240w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-768x768.jpg 768w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego.jpg 1080w\" sizes=\"(max-width: 435px) 100vw, 435px\" \/><\/figure><\/div>\n\n\n<p>A v\u00edtima foi identificada como Alexandre Ferreira da Silva, conhecido como &#8220;Beteu&#8221;, de 27 anos de idade.<\/p>\n\n\n\n<p>Ainda de acordo com informa\u00e7\u00f5es, os suspeitos da autoria do crime chegaram ao local onde Alexandre trabalhava em uma motocicleta efetuando v\u00e1rios disparos de arma de fogo. Em seguida, os criminosos fugiram para um destino ignorado. Alexandre evoluiu a \u00f3bito no local.\u00a0O mesmo era morador do conjunto habitacional Agripino Bernardo 3, na cidade de Tobias Barreto. <\/p>\n\n\n\n<p><em>Fonte: Portal Sergipano<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um ajudante de pedreiro foi assassinado a tiros enquanto trabalhava em uma obra, nesta ter\u00e7a-feira (16), no distrito da Lagoa Redonda, em Itapicuru-BA, na divisa com a cidade de Tobias Barreto-SE. At\u00e9 o momento da publica\u00e7\u00e3o desta reportagem, ningu\u00e9m havia sido preso.<\/p>\n","protected":false},"author":2,"featured_media":4880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[70,18,69,32,22],"tags":[100,71,48,75,4178,4180,375,129,107,4181,206,132,230,169,106,203,120,51,109,88,47,111,190],"class_list":["post-55870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-itapicuru","category-noticias2","category-regiao","category-seguranca","tag-adustina","tag-antas","tag-araci","tag-cicero-dantas","tag-cipo-2","tag-crisopolis-2","tag-disparos-de-arma-de-fogo","tag-euclides-da-cunha","tag-fatima","tag-heliopolis-2","tag-homicidio","tag-itapicuru","tag-jeremoabo","tag-morte","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/55870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=55870"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/55870\/revisions"}],"predecessor-version":[{"id":55871,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/55870\/revisions\/55871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/4880"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=55870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=55870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=55870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}