{"id":56450,"date":"2024-05-13T18:01:00","date_gmt":"2024-05-13T21:01:00","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=56450"},"modified":"2024-05-13T06:42:01","modified_gmt":"2024-05-13T09:42:01","slug":"jovem-morre-apos-sofrer-descarga-eletrica-em-cerca-durante-encontro-de-vaqueiros-em-teofilandia-ba","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2024\/05\/13\/jovem-morre-apos-sofrer-descarga-eletrica-em-cerca-durante-encontro-de-vaqueiros-em-teofilandia-ba\/","title":{"rendered":"Jovem morre ap\u00f3s sofrer descarga el\u00e9trica em cerca durante encontro de vaqueiros em Teofil\u00e2ndia-BA"},"content":{"rendered":"\n<p>Um jovem de 19 anos, identificado como Rodrigo da Silva Pereira, morreu no s\u00e1bado (11) ap\u00f3s sofrer uma descarga el\u00e9trica durante um encontro de vaqueiros no povoado Ipoeira, zona rural de Teofil\u00e2ndia, cidade da regi\u00e3o sisaleira da Bahia.<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-1024x1024.jpg\" alt=\"\" class=\"wp-image-55693\" width=\"430\" height=\"430\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-1024x1024.jpg 1024w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-240x240.jpg 240w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-768x768.jpg 768w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego.jpg 1080w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/><\/figure><\/div>\n\n\n<p>Segundo informa\u00e7\u00f5es da Pol\u00edcia Militar, testemunhas relataram que o jovem estava cavalgando quando o animal encostou em uma cerca da casa de farinha do povoado e recebeu um choque el\u00e9trico. Ao tentar se segurar na cerca para evitar a queda, Rodrigo tamb\u00e9m foi eletrocutado, possivelmente por uma liga\u00e7\u00e3o clandestina.<\/p>\n\n\n\n<p>Ele foi levado para a Unidade de Pronto Atendimento (UPA) de Araci, munic\u00edpio vizinho a Teofil\u00e2ndia. No entanto, chegou sem sinais vitais e teve o \u00f3bito por choque el\u00e9trico atestado pelo m\u00e9dico plantonista, segundo a PM.<\/p>\n\n\n\n<p><em>Fonte: Not\u00edcias de Santaluz<\/em><em><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um jovem de 19 anos, identificado como Rodrigo da Silva Pereira, morreu no s\u00e1bado (11) ap\u00f3s sofrer uma descarga el\u00e9trica durante um encontro de vaqueiros no povoado Ipoeira, zona rural de Teofil\u00e2ndia, cidade da regi\u00e3o sisaleira da Bahia.<\/p>\n","protected":false},"author":2,"featured_media":56445,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[41,33,70,69,32],"tags":[100,71,48,3145,1710,75,4178,4180,3365,129,107,4181,132,230,169,106,203,120,51,109,88,47,111,190],"class_list":["post-56450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-araci","category-bahia","category-destaques","category-noticias2","category-regiao","tag-adustina","tag-antas","tag-araci","tag-cavalgada","tag-choque-eletrico","tag-cicero-dantas","tag-cipo-2","tag-crisopolis-2","tag-descarga-eletrica","tag-euclides-da-cunha","tag-fatima","tag-heliopolis-2","tag-itapicuru","tag-jeremoabo","tag-morte","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/56450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=56450"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/56450\/revisions"}],"predecessor-version":[{"id":56451,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/56450\/revisions\/56451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/56445"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=56450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=56450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=56450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}