{"id":56452,"date":"2024-05-13T18:02:00","date_gmt":"2024-05-13T21:02:00","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=56452"},"modified":"2024-05-13T06:45:36","modified_gmt":"2024-05-13T09:45:36","slug":"com-retorno-de-chuva-forte-no-rs-populacao-deve-buscar-areas-seguras","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2024\/05\/13\/com-retorno-de-chuva-forte-no-rs-populacao-deve-buscar-areas-seguras\/","title":{"rendered":"Com retorno de chuva forte no RS, popula\u00e7\u00e3o deve buscar \u00e1reas seguras"},"content":{"rendered":"\n<p><strong><em>H\u00e1 risco de inunda\u00e7\u00e3o severa nos vales do Taquari e do Ca\u00ed<\/em><\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Com as chuvas intensas que voltaram a cair em diversos munic\u00edpios do Rio Grande do Sul na noite de s\u00e1bado (11), inclusive na capital, Porto Alegre, a Defesa Civil ga\u00facha emite novos alertas para que a popula\u00e7\u00e3o busque por \u00e1reas seguras.<\/p>\n\n\n\n<p>Entre as regi\u00f5es com <strong><em>&#8220;risco de inunda\u00e7\u00e3o severa&#8221;<\/em><\/strong> est\u00e3o os vales do Taquari e do Ca\u00ed, de acordo com os alertas mais recentes da Defesa Civil. <strong><em>\u201cQuem mora em regi\u00f5es pr\u00f3ximas, ou em \u00e1reas com hist\u00f3rico de alagamentos ou inunda\u00e7\u00f5es deve sair com anteced\u00eancia, de forma ordenada, buscando um local seguro para permanecer\u201d<\/em><\/strong>, orienta o \u00f3rg\u00e3o.<\/p>\n\n\n\n<p>Na noite de s\u00e1bado, o governador do Rio Grande do Sul, Eduardo Leite, alertou que os rios Taquari, Jacu\u00ed, dos Sinos e Ca\u00ed devem voltar a ter eleva\u00e7\u00e3o de n\u00edvel, ap\u00f3s leve recuo nos \u00faltimos dias. <strong><em>\u201cEspalhem essa informa\u00e7\u00e3o\u201d<\/em><\/strong>, pediu Eduardo Leite em v\u00eddeo publicado nas contas oficiais do governo nas redes sociais.<\/p>\n\n\n\n<p>Na regi\u00e3o metropolitana de Porto Alegre, o prefeito de Canoas, Jairo Jorge, tamb\u00e9m fez um apelo, neste domingo (12), para que quem voltou para casa ap\u00f3s o recuo das \u00e1guas volte a deixar os locais suscet\u00edveis a alagamentos. <strong><em>\u201cSaia imediatamente porque as \u00e1guas voltar\u00e3o, e a pessoa provavelmente ter\u00e1 que ser resgatada [se ficar]\u201d<\/em><\/strong>, disse ele em v\u00eddeo publicado na conta da prefeitura no Instagram.<\/p>\n\n\n\n<p>Segundo o balan\u00e7o mais recente do governo estadual, at\u00e9 o momento 76.399 pessoas foram resgatadas depois de ficarem ilhadas em diferentes pontos de alagamento, em algum dos 446 munic\u00edpios afetados. Foram salvos tamb\u00e9m 10.555 animais.<\/p>\n\n\n\n<p>Na capital ga\u00facha, o Lago Gua\u00edba voltou a apresentar eleva\u00e7\u00e3o de&nbsp;n\u00edvel neste domingo (12), com expectativa de&nbsp;<a href=\"http:\/\/https\/agenciabrasil.ebc.com.br\/geral\/noticia\/2024-05\/novo-aumento-do-guaiba-pode-superar-pico-anterior-preve-hidrologia\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>superar&nbsp;<\/strong><\/a>marcas acima de 5 metros, 2 acima da cota de inunda\u00e7\u00e3o, conforme a chegada da vaz\u00e3o pelos rios contribuintes e a atua\u00e7\u00e3o dos ventos.&nbsp;<\/p>\n\n\n\n<p>A Laguna dos Patos, ao sul, encontra-se tamb\u00e9m em n\u00edveis bem elevados e com tend\u00eancia de aumento significativo nos pontos monitorados das regi\u00f5es costeiras. A informa\u00e7\u00e3o \u00e9 da Sala de Situa\u00e7\u00e3o do Rio Grande do Sul.<\/p>\n\n\n\n<p>A Defesa Civil alerta as pessoas afetadas pelas cheias a n\u00e3o atravessar \u00e1reas alagadas a p\u00e9 ou de carro. <strong><em>\u201cProcure informa\u00e7\u00f5es com a Defesa Civil de sua cidade. Em caso de emerg\u00eancia, ligue 193\/190\u201d<\/em><\/strong>, recomenda o \u00f3rg\u00e3o.<\/p>\n\n\n\n<p>Pelos dados oficiais, foram registradas at\u00e9 o momento&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/geral\/noticia\/2024-05\/numero-de-vitimas-das-chuvas-sobe-para-143-no-rio-grande-do-sul\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>143 mortes<\/strong><\/a>&nbsp;causadas pelo mau tempo, com enchentes e enxurradas no Rio Grande do Sul, desde o fim de abril. H\u00e1 131 pessoas desaparecidas, e 537.380 ficaram desalojadas. Ao todo, 81.285 encontram-se em mais de 700 abrigos tempor\u00e1rios espalhados pelo estado.<\/p>\n\n\n\n<p><em>Fonte: Ag\u00eancia Brasil<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 risco de inunda\u00e7\u00e3o severa nos vales do Taquari e do Ca\u00ed<\/p>\n","protected":false},"author":2,"featured_media":56219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[34,70,69],"tags":[100,71,48,93,569,75,4178,4180,129,107,4181,132,230,106,203,120,51,109,88,47,854,111,190],"class_list":["post-56452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaques","category-noticias2","tag-adustina","tag-antas","tag-araci","tag-brasil","tag-chuva","tag-cicero-dantas","tag-cipo-2","tag-crisopolis-2","tag-euclides-da-cunha","tag-fatima","tag-heliopolis-2","tag-itapicuru","tag-jeremoabo","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-rio-grande-do-sul","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/56452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=56452"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/56452\/revisions"}],"predecessor-version":[{"id":56453,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/56452\/revisions\/56453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/56219"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=56452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=56452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=56452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}