{"id":63220,"date":"2024-10-24T23:57:15","date_gmt":"2024-10-25T02:57:15","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=63220"},"modified":"2024-10-25T00:15:25","modified_gmt":"2024-10-25T03:15:25","slug":"reu-por-assassinato-de-marielle-rivaldo-barbosa-nega-participacao-no-crime-nao-mato-uma-formiga","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2024\/10\/24\/reu-por-assassinato-de-marielle-rivaldo-barbosa-nega-participacao-no-crime-nao-mato-uma-formiga\/","title":{"rendered":"R\u00e9u por assassinato de Marielle, Rivaldo Barbosa nega participa\u00e7\u00e3o no crime: &#8216;N\u00e3o mato uma formiga&#8217;"},"content":{"rendered":"\n<p>Ex-chefe da Pol\u00edcia Civil presta depoimento ao STF<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-1024x1024.jpg\" alt=\"\" class=\"wp-image-55693\" width=\"435\" height=\"435\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-1024x1024.jpg 1024w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-240x240.jpg 240w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-768x768.jpg 768w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego.jpg 1080w\" sizes=\"(max-width: 435px) 100vw, 435px\" \/><\/figure><\/div>\n\n\n<p>O ex-chefe da Pol\u00edcia Civil do Rio de Janeiro Rivaldo Barbosa prestou depoimento virtual nesta quinta-feira (24) ao Supremo Tribunal Federal (STF). Rivaldo est\u00e1 preso no pres\u00eddio federal de Mossor\u00f3 (RN) e \u00e9 r\u00e9u na a\u00e7\u00e3o penal que trata do assassinato da vereadora Marielle Franco e do motorista Anderson Gomes, ocorrido em 2018, no Rio de Janeiro. Ele negou a participa\u00e7\u00e3o no crime, dizendo que n\u00e3o \u00e9 capaz de matar &#8220;uma formiga&#8221;.<\/p>\n\n\n\n<p>Rivaldo afirmou que conheceu Marielle quando virou chefe da Divis\u00e3o de Homic\u00eddios, em 2012. Na \u00e9poca, ela era assessora do ent\u00e3o deputado estadual Marcelo Freixo (hoje presidente da Embratur) na Comiss\u00e3o de Direito Humanos da Assembleia Legislativa do Rio de Janeiro (Alerj). De acordo com delegado, Marielle ajudava a intermediar o contato de familiares de pessoas mortas com a DH. Ele alegou ter &#8220;gratid\u00e3o&#8221; pelo trabalho dela.<\/p>\n\n\n\n<p>Ele ainda acrescentou que nunca falou com os irm\u00e3os Chiquinho e Domingos Braz\u00e3o, que s\u00e3o apontados como os mandantes do crime e tamb\u00e9m s\u00e3o r\u00e9us. &#8220;Eu nunca tive nada (com eles)&#8221;, afirmou. Rivaldo ainda ressaltou que a den\u00fancia apresentada pela Procuradoria-Geral da Rep\u00fablica (PGR), e aceita pelo STF, n\u00e3o aponta qual seria sua motiva\u00e7\u00e3o para o crime.<\/p>\n\n\n\n<p><em>Fonte: Metro 1<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ex-chefe da Pol\u00edcia Civil presta depoimento ao STF<\/p>\n","protected":false},"author":2,"featured_media":63206,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[34,70,69,22],"tags":[100,71,48,93,75,45,46,413,129,107,44,206,132,230,822,106,203,120,51,109,88,47,6996,111,190],"class_list":["post-63220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaques","category-noticias2","category-seguranca","tag-adustina","tag-antas","tag-araci","tag-brasil","tag-cicero-dantas","tag-cipo","tag-crisopolis","tag-depoimento","tag-euclides-da-cunha","tag-fatima","tag-heliopolis","tag-homicidio","tag-itapicuru","tag-jeremoabo","tag-marielle-franco","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-rivaldo-barbosa","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=63220"}],"version-history":[{"count":2,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63220\/revisions"}],"predecessor-version":[{"id":63222,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63220\/revisions\/63222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/63206"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=63220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=63220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=63220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}