{"id":63286,"date":"2024-10-28T07:02:00","date_gmt":"2024-10-28T10:02:00","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=63286"},"modified":"2024-10-28T00:54:37","modified_gmt":"2024-10-28T03:54:37","slug":"jovem-e-baleado-e-esfaqueado-apos-ser-convidado-para-fumar-maconha-na-zona-rural-de-araci-ba","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2024\/10\/28\/jovem-e-baleado-e-esfaqueado-apos-ser-convidado-para-fumar-maconha-na-zona-rural-de-araci-ba\/","title":{"rendered":"Jovem \u00e9 baleado e esfaqueado ap\u00f3s ser convidado para fumar maconha, na zona rural de Araci-BA"},"content":{"rendered":"\n<p>Um jovem de 24 anos sofreu uma tentativa de homic\u00eddio na sexta-feira (25) na zona rural de Araci, na regi\u00e3o sisaleira da Bahia. Segundo a Pol\u00edcia Militar, ele contou que estava indo fumar maconha com um colega no povoado Querer\u00e1, quando o suspeito, de maneira inesperada, atirou com uma espingarda artesanal na parte de tr\u00e1s de sua cabe\u00e7a.<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"348\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/07\/Real-Diversao-2024-1024x348.jpg\" alt=\"\" class=\"wp-image-58229\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/07\/Real-Diversao-2024-1024x348.jpg 1024w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/07\/Real-Diversao-2024-706x240.jpg 706w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/07\/Real-Diversao-2024-768x261.jpg 768w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/07\/Real-Diversao-2024.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>O jovem contou ainda que, mesmo ferido, reagiu e entrou em luta corporal com o colega, mas acabou sendo esfaqueado nas costas durante a briga.<\/p>\n\n\n\n<p>A PM informou que o jovem conseguiu fugir e procurou atendimento na UPA da cidade, onde ficou em observa\u00e7\u00e3o. O estado de sa\u00fade dele n\u00e3o foi informado. A Pol\u00edcia Civil foi acionada para investigar o caso.<\/p>\n\n\n\n<p><em>Fonte: Not\u00edcias de Santaluz<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um jovem de 24 anos sofreu uma tentativa de homic\u00eddio na sexta-feira (25) na zona rural de Araci, na regi\u00e3o sisaleira da Bahia. Segundo a Pol\u00edcia Militar, ele contou que estava indo fumar maconha com um colega no povoado Querer\u00e1, quando o suspeito, de maneira inesperada, atirou com uma espingarda artesanal na parte de tr\u00e1s &hellip;<\/p>\n","protected":false},"author":2,"featured_media":56445,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[41,70,69,32,22],"tags":[100,71,48,75,45,46,128,2115,129,492,107,44,132,230,106,203,120,51,109,88,47,111,105,190],"class_list":["post-63286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-araci","category-destaques","category-noticias2","category-regiao","category-seguranca","tag-adustina","tag-antas","tag-araci","tag-cicero-dantas","tag-cipo","tag-crisopolis","tag-disparo-de-arma-de-fogo","tag-drogas","tag-euclides-da-cunha","tag-facada","tag-fatima","tag-heliopolis","tag-itapicuru","tag-jeremoabo","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-sitio-do-quinto","tag-tentativa-de-homicidio","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=63286"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63286\/revisions"}],"predecessor-version":[{"id":63287,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/63286\/revisions\/63287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/56445"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=63286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=63286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=63286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}