{"id":64185,"date":"2024-11-11T17:01:00","date_gmt":"2024-11-11T20:01:00","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=64185"},"modified":"2024-11-11T13:11:38","modified_gmt":"2024-11-11T16:11:38","slug":"candidato-a-prefeitura-de-ribeira-do-pombal-ba-perde-prazo-para-prestacao-de-contas-e-afirma-nao-haver-risco-de-inelegibilidade","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2024\/11\/11\/candidato-a-prefeitura-de-ribeira-do-pombal-ba-perde-prazo-para-prestacao-de-contas-e-afirma-nao-haver-risco-de-inelegibilidade\/","title":{"rendered":"Candidato \u00e0 Prefeitura de Ribeira do Pombal-BA perde prazo para presta\u00e7\u00e3o de contas, e afirma n\u00e3o haver risco de inelegibilidade"},"content":{"rendered":"\n<p>O candidato da oposi\u00e7\u00e3o ao cargo de prefeito de Ribeira do Pombal-BA, Brenno de Melo Gomes Calasans (Brenno de Dad\u00e1), pelo partido PP, enfrenta uma situa\u00e7\u00e3o delicada em rela\u00e7\u00e3o \u00e0 sua elegibilidade nas elei\u00e7\u00f5es de 2024. De acordo com um documento emitido pelo Tribunal Superior Eleitoral (TSE), Brenno n\u00e3o apresentou as contas finais de campanha dentro do prazo estipulado.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>A Certid\u00e3o de Inadimpl\u00eancia, divulgada no dia 6 de novembro de 2024, confirma que Brenno n\u00e3o cumpriu com a obrigatoriedade de presta\u00e7\u00e3o de contas referente \u00e0s elei\u00e7\u00f5es deste ano, conforme previsto na Resolu\u00e7\u00e3o TSE n\u00ba 23.607\/2019.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/Sabino-Tijolo-576x1024.jpg\" alt=\"\" class=\"wp-image-56164\" width=\"363\" height=\"645\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/Sabino-Tijolo-576x1024.jpg 576w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/Sabino-Tijolo-135x240.jpg 135w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/Sabino-Tijolo.jpg 591w\" sizes=\"(max-width: 363px) 100vw, 363px\" \/><\/figure><\/div>\n\n\n<p><strong>O Que Diz a Lei?<\/strong><\/p>\n\n\n\n<p>Segundo o artigo 83 da Resolu\u00e7\u00e3o TSE n\u00ba 23.607\/2019, <strong><em>\u201ca Justi\u00e7a Eleitoral notificar\u00e1 o candidato que n\u00e3o apresentar as contas de campanha no prazo legal, permitindo sua manifesta\u00e7\u00e3o e concess\u00e3o de um prazo para regulariza\u00e7\u00e3o\u201d.<\/em><\/strong> Contudo, a falta de presta\u00e7\u00e3o de contas, mesmo ap\u00f3s notifica\u00e7\u00e3o, pode levar \u00e0 suspens\u00e3o dos direitos pol\u00edticos, impedindo o candidato de concorrer em futuras elei\u00e7\u00f5es enquanto a situa\u00e7\u00e3o estiver irregular.<\/p>\n\n\n\n<p>Al\u00e9m disso, o artigo estabelece que candidatos inadimplentes n\u00e3o recebem a quita\u00e7\u00e3o eleitoral, que \u00e9 essencial para validar futuras candidaturas.<\/p>\n\n\n\n<p>Brenno pode ainda tentar reverter os preju\u00edzos que essa falta de presta\u00e7\u00e3o podem causar.<\/p>\n\n\n\n<p><strong>Jurisprud\u00eancia<\/strong><\/p>\n\n\n\n<p>O candidato Brenno de Melo Gomes Calasans apresentou um print nas redes sociais com jurisprud\u00eancia do Tribunal Superior Eleitoral (TSE) para se defender contra poss\u00edveis penalidades devido ao atraso na entrega de sua presta\u00e7\u00e3o de contas. Segundo o documento, o TSE considera que o envio fora do prazo configura uma <strong>\u201cirregularidade formal\u201d<\/strong>, pass\u00edvel de aprova\u00e7\u00e3o com ressalvas, desde que n\u00e3o prejudique a transpar\u00eancia e fiscaliza\u00e7\u00e3o das contas.<\/p>\n\n\n\n<p>Com essa defesa, Brenno argumenta que seu atraso n\u00e3o comprometeu a lisura do processo e, portanto, suas contas poderiam ser aprovadas com ressalvas, o que manteria sua quita\u00e7\u00e3o eleitoral e preservaria sua elegibilidade para futuras elei\u00e7\u00f5es.<\/p>\n\n\n\n<p>A decis\u00e3o agora depende da an\u00e1lise da Justi\u00e7a Eleitoral, que avaliar\u00e1 o impacto do atraso.<\/p>\n\n\n\n<p>Procurado pela reportagem o pol\u00edtico n\u00e3o respondeu ao contato at\u00e9 o fechamento desta mat\u00e9ria.<\/p>\n\n\n\n<p><em>Fonte: Dia a Dia Nordeste<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O candidato da oposi\u00e7\u00e3o ao cargo de prefeito de Ribeira do Pombal-BA, Brenno de Melo Gomes Calasans (Brenno de Dad\u00e1), pelo partido PP, enfrenta uma situa\u00e7\u00e3o delicada em rela\u00e7\u00e3o \u00e0 sua elegibilidade nas elei\u00e7\u00f5es de 2024. De acordo com um documento emitido pelo Tribunal Superior Eleitoral (TSE), Brenno n\u00e3o apresentou as contas finais de campanha &hellip;<\/p>\n","protected":false},"author":2,"featured_media":64170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[70,69,21,32,3],"tags":[100,71,48,7143,75,4178,4180,129,107,4181,132,230,106,203,120,51,672,109,88,47,111,190],"class_list":["post-64185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-noticias2","category-politica","category-regiao","category-ribeira-do-pombal","tag-adustina","tag-antas","tag-araci","tag-brenno-de-dada","tag-cicero-dantas","tag-cipo-2","tag-crisopolis-2","tag-euclides-da-cunha","tag-fatima","tag-heliopolis-2","tag-itapicuru","tag-jeremoabo","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-prestacao-de-contas","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/64185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=64185"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/64185\/revisions"}],"predecessor-version":[{"id":64186,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/64185\/revisions\/64186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/64170"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=64185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=64185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=64185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}