{"id":67055,"date":"2025-01-06T06:00:00","date_gmt":"2025-01-06T09:00:00","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=67055"},"modified":"2025-01-06T00:45:59","modified_gmt":"2025-01-06T03:45:59","slug":"funcionario-da-revalle-morre-em-acidente-no-centro-de-jeremoabo-ba-motorista-e-preso-suspeito-de-embriaguez","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2025\/01\/06\/funcionario-da-revalle-morre-em-acidente-no-centro-de-jeremoabo-ba-motorista-e-preso-suspeito-de-embriaguez\/","title":{"rendered":"Funcion\u00e1rio da Revalle morre em acidente no centro de Jeremoabo-BA; motorista \u00e9 preso suspeito de embriaguez"},"content":{"rendered":"\n<p>Na noite deste s\u00e1bado (4), por volta das 21h30, um grave acidente envolvendo uma moto e um carro no centro de Jeremoabo-BA terminou com a morte do motoqueiro Denis Jesus de Souza. Ele trabalhava como entregador de cerveja na empresa Revalle.<\/p>\n\n\n\n<!--more-->\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"372\" height=\"786\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/03\/Real-10x-100-juros-2024.jpg\" alt=\"\" class=\"wp-image-55190\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/03\/Real-10x-100-juros-2024.jpg 372w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/03\/Real-10x-100-juros-2024-114x240.jpg 114w\" sizes=\"(max-width: 372px) 100vw, 372px\" \/><\/figure><\/div>\n\n\n<p>O acidente ocorreu ao lado da Pizzaria GranPastelli, pr\u00f3ximo ao local conhecido como S\u00e3o Geraldo e quase em frente \u00e0 sede da Guarda Municipal. O motorista do ve\u00edculo envolvido foi detido no local pela Guarda Municipal, que acionou a Pol\u00edcia Militar para a pris\u00e3o.<\/p>\n\n\n\n<p>Testemunhas relataram que o condutor estava visivelmente alcoolizado no momento da pris\u00e3o. Um v\u00eddeo que circula nas redes sociais mostra uma grande aglomera\u00e7\u00e3o de pessoas em frente \u00e0 Guarda Municipal e gritos de indigna\u00e7\u00e3o, como <strong><em>\u201cvoc\u00ea tirou a vida do rapaz\u201d<\/em><\/strong>.<\/p>\n\n\n\n<p>A empresa Revalle, onde Denis trabalhava, emitiu uma nota de pesar lamentando a perda do colaborador. <strong><em>\u201cAgradecemos imensamente o tempo que o Denis fez parte do nosso time, ser\u00e1 sempre lembrado\u201d,<\/em><\/strong> declarou.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"720\" height=\"900\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2025\/01\/Acidente-em-Jeremoabo-2025.1.jpg\" alt=\"\" class=\"wp-image-67056\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2025\/01\/Acidente-em-Jeremoabo-2025.1.jpg 720w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2025\/01\/Acidente-em-Jeremoabo-2025.1-192x240.jpg 192w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure><\/div>\n\n\n<p><em>Fonte: Pa4<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite deste s\u00e1bado (4), por volta das 21h30, um grave acidente envolvendo uma moto e um carro no centro de Jeremoabo-BA terminou com a morte do motoqueiro Denis Jesus de Souza. Ele trabalhava como entregador de cerveja na empresa Revalle.<\/p>\n","protected":false},"author":2,"featured_media":67057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[70,9,69,32,22],"tags":[5463,100,71,48,75,4178,4180,129,107,4181,132,230,169,106,203,120,51,109,88,47,111,190],"class_list":["post-67055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-jeremoabo","category-noticias2","category-regiao","category-seguranca","tag-acidente-de-transito","tag-adustina","tag-antas","tag-araci","tag-cicero-dantas","tag-cipo-2","tag-crisopolis-2","tag-euclides-da-cunha","tag-fatima","tag-heliopolis-2","tag-itapicuru","tag-jeremoabo","tag-morte","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=67055"}],"version-history":[{"count":2,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67055\/revisions"}],"predecessor-version":[{"id":67059,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67055\/revisions\/67059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/67057"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=67055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=67055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=67055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}