{"id":67576,"date":"2025-01-13T14:26:31","date_gmt":"2025-01-13T17:26:31","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=67576"},"modified":"2025-01-13T14:28:26","modified_gmt":"2025-01-13T17:28:26","slug":"joias-sauditas-pf-envia-ao-supremo-imagens-e-depoimentos-colhidos-nos-eua","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2025\/01\/13\/joias-sauditas-pf-envia-ao-supremo-imagens-e-depoimentos-colhidos-nos-eua\/","title":{"rendered":"Joias sauditas: PF envia ao Supremo imagens e depoimentos colhidos nos EUA"},"content":{"rendered":"\n<p>Elementos devem ser usados em processo de julgamento que tem ex-presidente Jair Bolsonaro como indiciado<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>A Pol\u00edcia Federal (PF) enviou ao Supremo Tribunal Federal (STF) um pen drive com imagens e depoimentos colhidos nos Estados Unidos na investiga\u00e7\u00e3o que apurou a venda no exterior de joias sauditas recebidas pelo ent\u00e3o governo de Jair Bolsonaro (PL).<\/p>\n\n\n\n<p>Em julho do ano passado, o ex-presidente Bolsonaro e mais 11 pessoas&nbsp;foram indiciadas&nbsp;nesse inqu\u00e9rito. O caso foi enviado ao STF e est\u00e1 com vistas \u00e0 Procuradoria-Geral da Rep\u00fablica (PGR) para poss\u00edvel den\u00fancia.<\/p>\n\n\n\n<p>Os documentos e depoimentos foram levantados no contexto do Acordo de Assist\u00eancia Jur\u00eddica em Mat\u00e9ria Penal (MLAT), firmado entre a PF e o Departamento de Justi\u00e7a dos Estados Unidos (DOJ), no ano passado.<\/p>\n\n\n\n<p>O MLAT \u00e9 um tratado bilateral que facilita a coopera\u00e7\u00e3o entre autoridades de diferentes pa\u00edses e \u00e9 um instrumento para a prote\u00e7\u00e3o de dados pessoais e para que autoridades brasileiras possam compartilhar dados com autoridades estrangeiras.<\/p>\n\n\n\n<p>Em abril do ano passado, uma equipe da PF foi aos Estados Unidos e trabalhou em conjunto com o FBI (Federal Bureau of Investigation) no caso. Os agentes&nbsp;visitaram quatro cidades americanas:&nbsp;Miami, Orlando, Nova York e Wilson Grove.<\/p>\n\n\n\n<p>Os policiais foram em lojas onde auxiliares de Bolsonaro teriam vendido os itens valiosos da Presid\u00eancia, com ajuda do tenente-coronel Mauro Cid, ex-ajudante de ordens do ex-presidente. Cid, em colabora\u00e7\u00e3o com a PF e o FBI, detalhou endere\u00e7os e nomes dos locais onde ocorreram as negocia\u00e7\u00f5es.<\/p>\n\n\n\n<p>Imagens de c\u00e2meras de seguran\u00e7a foram confiscadas para ajudar no inqu\u00e9rito, \u00e0 \u00e9poca. O material mostra, por exemplo, Mauro Cid negociando a venda de rel\u00f3gios.<\/p>\n\n\n\n<p>Anota\u00e7\u00f5es, notas fiscais e fotos tamb\u00e9m foram apreendidos, com autoriza\u00e7\u00e3o das autoridades norte-americanas. E agora repassados ao STF.<\/p>\n\n\n\n<p>Os elementos enviados ao Supremo pela PF devem embasar o processo de poss\u00edvel julgamento do ex-presidente Bolsonaro na Corte, caso a PGR ofere\u00e7a den\u00fancia e o STF aceite, tornando o r\u00e9u na a\u00e7\u00e3o.<\/p>\n\n\n\n<p>Ap\u00f3s o indiciamento, no ano passado, os advogados de Bolsonaro afirmaram que os presentes ofertados \u00e0 Presid\u00eancia da Rep\u00fablica <strong><em>\u201cobedecem a um r\u00edgido protocolo de tratamento e cataloga\u00e7\u00e3o\u201d,<\/em><\/strong> sobre o qual <strong><em>\u201co chefe do Executivo n\u00e3o tem qualquer inger\u00eancia, direta ou indireta\u201d.<\/em><\/strong><\/p>\n\n\n\n<p>O documento chamou o inqu\u00e9rito das joias de \u201cins\u00f3lito\u201d, por voltar-se \u201cs\u00f3 e somente ao Governo Bolsonaro, ignorando situa\u00e7\u00f5es id\u00eanticas havidas em governos anteriores\u201d.<\/p>\n\n\n\n<p>A defesa disse, ainda, que Bolsonaro&nbsp;compareceu de forma espont\u00e2nea, ap\u00f3s ser noticiado da necessidade da restitui\u00e7\u00e3o, e decidiu que os bens fossem devolvidos.<\/p>\n\n\n\n<p><em>Fonte: CNN<\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elementos devem ser usados em processo de julgamento que tem ex-presidente Jair Bolsonaro como indiciado<\/p>\n","protected":false},"author":2,"featured_media":67590,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[34,70,69,21],"tags":[100,71,48,93,75,4178,4180,327,129,107,4181,132,1395,230,5980,106,203,120,51,173,109,88,47,111,216,190],"class_list":["post-67576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaques","category-noticias2","category-politica","tag-adustina","tag-antas","tag-araci","tag-brasil","tag-cicero-dantas","tag-cipo-2","tag-crisopolis-2","tag-eua","tag-euclides-da-cunha","tag-fatima","tag-heliopolis-2","tag-itapicuru","tag-jair-bolsonaro","tag-jeremoabo","tag-joias","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-policia-federal","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-sitio-do-quinto","tag-stf","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=67576"}],"version-history":[{"count":2,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67576\/revisions"}],"predecessor-version":[{"id":67614,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67576\/revisions\/67614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/67590"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=67576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=67576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=67576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}