{"id":67729,"date":"2025-01-14T23:30:18","date_gmt":"2025-01-15T02:30:18","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=67729"},"modified":"2025-01-14T23:30:19","modified_gmt":"2025-01-15T02:30:19","slug":"presidente-afastado-da-coreia-do-sul-e-preso-apos-segunda-operacao-policial-diz-agencia","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2025\/01\/14\/presidente-afastado-da-coreia-do-sul-e-preso-apos-segunda-operacao-policial-diz-agencia\/","title":{"rendered":"Presidente afastado da Coreia do Sul \u00e9 preso ap\u00f3s segunda opera\u00e7\u00e3o policial, diz ag\u00eancia"},"content":{"rendered":"\n<p>Yoon Suk Yeol sofreu impeachment em dezembro ap\u00f3s decretar Lei Marcial no pa\u00eds<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>O presidente da Coreia do Sul Yoon Suk Yeol foi preso nesta quarta-feira (15), no hor\u00e1rio local, ap\u00f3s o cumprimento de um mandado por parte das autoridades sul-coreanas, informou a ag\u00eancia de not\u00edcias Yonhap.<\/p>\n\n\n\n<p>Uma ag\u00eancia anticorrup\u00e7\u00e3o que investiga o\u00a0breve decreto de Lei Marcial em 3 de dezembro\u00a0tamb\u00e9m confirmou a pris\u00e3o de Yoon em uma declara\u00e7\u00e3o, de acordo com a Reuters.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-1024x1024.jpg\" alt=\"\" class=\"wp-image-55693\" width=\"425\" height=\"425\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-1024x1024.jpg 1024w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-240x240.jpg 240w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego-768x768.jpg 768w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2024\/04\/autoescola-emprego.jpg 1080w\" sizes=\"(max-width: 425px) 100vw, 425px\" \/><\/figure><\/div>\n\n\n<p>Esta foi a\u00a0segunda tentativa de prender o Yoon Suk Yeol,\u00a0que est\u00e1 afastado do cargo. As autoridades conseguiram entrar na resid\u00eancia presidencial nesta quarta ap\u00f3s confrontos com apoiadores de Yoon que fizeram uma barreira na entrada da casa do presidente afastado.<\/p>\n\n\n\n<p>Yoon estava sob investiga\u00e7\u00e3o criminal por poss\u00edveis acusa\u00e7\u00f5es de insurrei\u00e7\u00e3o, em fun\u00e7\u00e3o de sua tentativa de impor a Lei Marcial em dezembro.<\/p>\n\n\n\n<p>O mandado foi cumprido por funcion\u00e1rios do Gabinete de Investiga\u00e7\u00e3o de Corrup\u00e7\u00e3o para Altos Funcion\u00e1rios, \u00f3rg\u00e3o que lidera uma equipe de investigadores que incluem a pol\u00edcia e promotores.<\/p>\n\n\n\n<p>Anteriormente a pol\u00edcia j\u00e1 havia tentado, mas n\u00e3o conseguiu invadir o gabinete presidencial como parte da investiga\u00e7\u00e3o devido ao bloqueio do servi\u00e7o de seguran\u00e7a de Yoon ao acesso.<\/p>\n\n\n\n<p>Durante semanas, o presidente afastado ficou confinado na resid\u00eancia fortificada, cercado por sua equipe do Servi\u00e7o de Seguran\u00e7a Presidencial, evitando ser preso enquanto enfrenta diversas investiga\u00e7\u00f5es e um julgamento de impeachment ap\u00f3s seu breve decreto.<\/p>\n\n\n\n<p>Os advogados de Yoon reiteraram que o mandado de pris\u00e3o \u00e9 \u201cilegal e inv\u00e1lido\u201d e prometeram tomar medidas legais contra sua execu\u00e7\u00e3o. Os apoiadores do presidente afastado tamb\u00e9m insistiram que as a\u00e7\u00f5es que est\u00e3o sendo tomadas contra ele s\u00e3o contr\u00e1rias \u00e0 lei sul-coreana.<\/p>\n\n\n\n<p>Yoon permaneceu desafiador diante das investiga\u00e7\u00f5es e do julgamento de impeachment em andamento por um dos mais altos tribunais do pa\u00eds.<\/p>\n\n\n\n<p>O ex-promotor que virou pol\u00edtico foi destitu\u00eddo de seus poderes presidenciais no m\u00eas passado depois que o\u00a0parlamento votou por seu impeachment. O Tribunal Constitucional do pa\u00eds agora tem a palavra final sobre se ele ser\u00e1 formalmente removido ou reintegrado.<\/p>\n\n\n\n<p>O primeiro dia do\u00a0julgamento de impeachment de Yoon\u00a0come\u00e7ou nesta ter\u00e7a-feira (14), mas terminou depois de apenas quatro minutos quando o presidente afastado se recusou a aparecer. O julgamento, que pode levar at\u00e9 seis meses, est\u00e1 programado para ser retomado nesta quinta-feira (16) e prosseguir\u00e1 com ou sem a presen\u00e7a de Yoon.<\/p>\n\n\n\n<p>Nas semanas desde a declara\u00e7\u00e3o da Lei Marcial, o pa\u00eds tem estado em desordem pol\u00edtica com o parlamento tamb\u00e9m votando pelo impeachment de seu primeiro-ministro e presidente interino Han Duck-soo, poucas semanas ap\u00f3s ter votado pelo impeachment de Yoon. O ministro das finan\u00e7as Choi Sang-mok \u00e9 agora presidente interino.<\/p>\n\n\n\n<p>O Tribunal Constitucional prometeu considerar o caso contra Yoon como uma \u201cprioridade m\u00e1xima\u201d, juntamente com outros casos de impeachment que a oposi\u00e7\u00e3o tem movido contra integrantes do governo de Yoon, incluindo o ministro da Justi\u00e7a, promotores e outros altos funcion\u00e1rios.<\/p>\n\n\n\n<p><strong>O que \u00e9 a Lei Marcial<\/strong><\/p>\n\n\n\n<p>A Lei Marcial \u00e9 adotada em situa\u00e7\u00f5es \u201cexcepcionais\u201d, como a eclos\u00e3o de uma guerra ou em caso de desastres naturais e cat\u00e1strofes, por exemplo. Ela permite, entre outras coisas, que as autoridades restrinjam a circula\u00e7\u00e3o e estabele\u00e7am toques de recolher, confinando as pessoas em suas casas.<\/p>\n\n\n\n<p>O portal da C\u00e2mara dos Deputados do Brasil a define como algo que \u201csubmete, durante o estado de guerra, todas as pessoas a regime especial, com a suspens\u00e3o de garantias civis e pol\u00edticas, asseguradas, em tempos normais, pelas leis constitucionais\u201d.<\/p>\n\n\n\n<p><em>Fonte: CNN<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yoon Suk Yeol sofreu impeachment em dezembro ap\u00f3s decretar Lei Marcial no pa\u00eds<\/p>\n","protected":false},"author":2,"featured_media":67730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[70,35,69,21],"tags":[100,71,48,75,4178,341,4180,129,107,4181,132,230,339,106,203,120,51,94,77,109,88,47,111,190,7726],"class_list":["post-67729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-mundo","category-noticias2","category-politica","tag-adustina","tag-antas","tag-araci","tag-cicero-dantas","tag-cipo-2","tag-coreia-do-sul","tag-crisopolis-2","tag-euclides-da-cunha","tag-fatima","tag-heliopolis-2","tag-itapicuru","tag-jeremoabo","tag-mundo","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-presidente","tag-preso","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-sitio-do-quinto","tag-tucano","tag-yoon-suk-yeol"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=67729"}],"version-history":[{"count":2,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67729\/revisions"}],"predecessor-version":[{"id":67741,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/67729\/revisions\/67741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/67730"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=67729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=67729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=67729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}