{"id":74088,"date":"2025-07-27T14:12:32","date_gmt":"2025-07-27T17:12:32","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=74088"},"modified":"2025-07-27T14:12:33","modified_gmt":"2025-07-27T17:12:33","slug":"bahia-tem-cinco-cidades-entre-as-10-mais-violentas-do-brasil-veja-lista","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2025\/07\/27\/bahia-tem-cinco-cidades-entre-as-10-mais-violentas-do-brasil-veja-lista\/","title":{"rendered":"Bahia tem cinco cidades entre as 10 mais violentas do Brasil; veja lista"},"content":{"rendered":"\n<p>Cinco cidades baianas est\u00e3o no ranking das 10 mais violentas de todo Brasil e o estado \u00e9 o mais violento do Brasil quando considerados os n\u00fameros absolutos.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p> Os dados s\u00e3o do Anu\u00e1rio Brasileiro de Seguran\u00e7a P\u00fablica 2024, produzido pelo F\u00f3rum Brasileiro de Seguran\u00e7a P\u00fablica, e divulgados nesta quinta-feira (24). Quando considerados os dados de proporcionalidade habitacional, o estado \u00e9 o segundo mais violento do Brasil e fica atr\u00e1s apenas do Amap\u00e1. A cidade de Jequi\u00e9, no sudoeste da Bahia, \u00e9 a segunda mais violenta do Brasil e ficou atr\u00e1s apenas de Maranguape, no Cear\u00e1. Feira de Santana, a segunda maior cidade do estado, tamb\u00e9m integra o ranking acompanhada de Juazeiro, Sim\u00f5es Filho e Cama\u00e7ari. Os dados divulgados nesta quinta s\u00e3o referentes aos n\u00fameros do ano passado e as taxas de viol\u00eancia s\u00e3o calculadas a cada 100 mil habitantes. Apesar da Bahia ocupar cinco das 10 posi\u00e7\u00f5es do ranking, houve uma diminui\u00e7\u00e3o de 8,4% no n\u00famero de mortes violentas no estado \u2013 em 2023, foram 5.579, enquanto em 2024 foram 6.036. No relat\u00f3rio de 2023, seis cidades baianas estavam entre as 10 mais violentas do pa\u00eds. Os dados desse ano tamb\u00e9m demonstram diminui\u00e7\u00e3o nos \u00edndices de viol\u00eancia em pelo menos quatro cidades: Jequi\u00e9, Cama\u00e7ari, Sim\u00f5es Filho e Feira de Santana. A cidade de Juazeiro registrou um crescimento em rela\u00e7\u00e3o aos dados do \u00faltimo ano. Conforme apura\u00e7\u00e3o do F\u00f3rum Brasileiro de Seguran\u00e7a P\u00fablica, as cidades mais violentas do pa\u00eds sofrem com disputas de fac\u00e7\u00f5es pelo controle do tr\u00e1fico de drogas. Em nota, a Secretaria de Seguran\u00e7a P\u00fablica da Bahia (SSP-BA) informou que nos \u00faltimos dois anos houve redu\u00e7\u00e3o no n\u00famero de mortes violentas: 6% em 2023 e 8,2% em 2024. A SSP tamb\u00e9m afirmou que a For\u00e7a Integrada de Combate ao Crime Organizado (FICCO) fez um trabalho espec\u00edfico em Jequi\u00e9 e que, depois disso, n\u00e3o houve registro de aumento de mortes violentas na cidade. A secretaria n\u00e3o especificou qual foi o tipo de trabalho, nem quando ele foi realizado.<\/p>\n\n\n\n<p><em>Fonte: A voz do campo<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cinco cidades baianas est\u00e3o no ranking das 10 mais violentas de todo Brasil e o estado \u00e9 o mais violento do Brasil quando considerados os n\u00fameros absolutos.<\/p>\n","protected":false},"author":2,"featured_media":74082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[33,34,70,69,22],"tags":[100,71,48,54,93,227,75,4178,4180,129,107,377,4181,132,1731,230,445,106,203,120,51,109,88,47,399,111,190,4943],"class_list":["post-74088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","category-brasil","category-destaques","category-noticias2","category-seguranca","tag-adustina","tag-antas","tag-araci","tag-bahia","tag-brasil","tag-camacari","tag-cicero-dantas","tag-cipo-2","tag-crisopolis-2","tag-euclides-da-cunha","tag-fatima","tag-feira-de-santana","tag-heliopolis-2","tag-itapicuru","tag-jequie","tag-jeremoabo","tag-juazeiro","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-simoes-filho","tag-sitio-do-quinto","tag-tucano","tag-violencia-2"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=74088"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74088\/revisions"}],"predecessor-version":[{"id":74089,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/74088\/revisions\/74089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/74082"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=74088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=74088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=74088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}