{"id":79802,"date":"2026-05-12T18:47:00","date_gmt":"2026-05-12T21:47:00","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=79802"},"modified":"2026-05-12T18:47:02","modified_gmt":"2026-05-12T21:47:02","slug":"lula-diz-que-governo-criara-ministerio-da-seguranca-apos-aprovacao-da-pec-no-senado","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2026\/05\/12\/lula-diz-que-governo-criara-ministerio-da-seguranca-apos-aprovacao-da-pec-no-senado\/","title":{"rendered":"Lula diz que governo criar\u00e1 Minist\u00e9rio da Seguran\u00e7a ap\u00f3s aprova\u00e7\u00e3o da PEC no Senado"},"content":{"rendered":"\n<p>Declara\u00e7\u00e3o foi feita durante lan\u00e7amento do programa \u201cBrasil Contra o Crime Organizado\u201d, em Bras\u00edlia<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>O presidente Luiz In\u00e1cio Lula da Silva afirmou nesta ter\u00e7a-feira (12) que o governo federal pretende criar o Minist\u00e9rio da Seguran\u00e7a P\u00fablica ap\u00f3s a aprova\u00e7\u00e3o da PEC da Seguran\u00e7a pelo Senado. A declara\u00e7\u00e3o foi feita durante o lan\u00e7amento do programa \u201cBrasil Contra o Crime Organizado\u201d, no Pal\u00e1cio do Planalto, em Bras\u00edlia.<\/p>\n\n\n\n<p>Segundo Lula, a proposta \u00e9 considerada fundamental para redefinir a atua\u00e7\u00e3o da Uni\u00e3o na \u00e1rea da seguran\u00e7a p\u00fablica e ampliar a coopera\u00e7\u00e3o com os estados no combate \u00e0s fac\u00e7\u00f5es criminosas.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"480\" height=\"600\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2026\/05\/Real-Amor-de-Mae-2026.jpeg\" alt=\"\" class=\"wp-image-79671\" style=\"width:382px;height:auto\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2026\/05\/Real-Amor-de-Mae-2026.jpeg 480w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2026\/05\/Real-Amor-de-Mae-2026-192x240.jpeg 192w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure><\/div>\n\n\n<p>\u201cO dia que o Senado aprovar a PEC da Seguran\u00e7a, n\u00f3s criaremos o Minist\u00e9rio da Seguran\u00e7a P\u00fablica nesse pa\u00eds\u201d, declarou o presidente durante o evento.<\/p>\n\n\n\n<p>Atualmente, a seguran\u00e7a p\u00fablica est\u00e1 vinculada ao Minist\u00e9rio da Justi\u00e7a. Desde o in\u00edcio do mandato, Lula vinha evitando defender a cria\u00e7\u00e3o de uma pasta exclusiva para o setor, citando preocupa\u00e7\u00f5es pol\u00edticas, institucionais e o receio de ampliar a estrutura administrativa federal.<\/p>\n\n\n\n<p>Durante o discurso, o presidente afirmou que a Constitui\u00e7\u00e3o de 1988 concentrou a responsabilidade da seguran\u00e7a nos estados, mas argumentou que o avan\u00e7o do crime organizado exige maior participa\u00e7\u00e3o do governo federal.<\/p>\n\n\n\n<p>De acordo com Lula, o objetivo n\u00e3o \u00e9 retirar autonomia dos governadores ou das pol\u00edcias estaduais, mas fortalecer a\u00e7\u00f5es integradas entre Uni\u00e3o e estados. Ele tamb\u00e9m disse que organiza\u00e7\u00f5es criminosas se beneficiam da falta de articula\u00e7\u00e3o entre os entes federativos.<\/p>\n\n\n\n<p>O programa \u201cBrasil Contra o Crime Organizado\u201d foi apresentado como uma estrat\u00e9gia nacional para enfrentar fac\u00e7\u00f5es e combater esquemas de lavagem de dinheiro. O plano prev\u00ea maior integra\u00e7\u00e3o entre for\u00e7as de seguran\u00e7a e \u00f3rg\u00e3os de intelig\u00eancia.<\/p>\n\n\n\n<p>Entre os participantes do lan\u00e7amento estavam o ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Wellington C\u00e9sar Lima e Silva, o presidente da C\u00e2mara dos Deputados, Hugo Motta, e o procurador-geral da Rep\u00fablica, Paulo Gonet.<\/p>\n\n\n\n<p>A PEC da Seguran\u00e7a P\u00fablica foi aprovada pela C\u00e2mara dos Deputados em mar\u00e7o e aguarda despacho do presidente do Senado, Davi Alcolumbre, para come\u00e7ar a tramitar na Casa. O texto enfrenta resist\u00eancia de parlamentares da oposi\u00e7\u00e3o e de governadores que avaliam que a medida pode ampliar excessivamente o poder da Uni\u00e3o sobre a seguran\u00e7a p\u00fablica.<\/p>\n\n\n\n<p>A proposta prev\u00ea a constitucionaliza\u00e7\u00e3o do Sistema \u00danico de Seguran\u00e7a P\u00fablica (Susp) e mecanismos de coopera\u00e7\u00e3o entre os estados e o governo federal.<\/p>\n\n\n\n<p><em>Fonte: Metro1<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Declara\u00e7\u00e3o foi feita durante lan\u00e7amento do programa \u201cBrasil Contra o Crime Organizado\u201d, em Bras\u00edlia<\/p>\n","protected":false},"author":2,"featured_media":32169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[34,8473,69,22],"tags":[100,71,48,93,75,4178,4180,129,107,4181,132,230,303,106,203,120,51,199,109,88,47,623,111,190],"class_list":["post-79802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaque","category-noticias2","category-seguranca","tag-adustina","tag-antas","tag-araci","tag-brasil","tag-cicero-dantas","tag-cipo-2","tag-crisopolis-2","tag-euclides-da-cunha","tag-fatima","tag-heliopolis-2","tag-itapicuru","tag-jeremoabo","tag-lula","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-politica","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-seguranca-publica","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/79802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=79802"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/79802\/revisions"}],"predecessor-version":[{"id":79803,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/79802\/revisions\/79803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/32169"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=79802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=79802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=79802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}