{"id":80449,"date":"2026-07-14T22:30:19","date_gmt":"2026-07-15T01:30:19","guid":{"rendered":"https:\/\/www.portalalerta.com.br\/?p=80449"},"modified":"2026-07-14T22:30:20","modified_gmt":"2026-07-15T01:30:20","slug":"suspeitos-de-cometerem-homicidio-em-praca-publica-em-tucano-ba-sao-presos-durante-acao-conjunta-de-forcas-de-seguranca","status":"publish","type":"post","link":"https:\/\/www.portalalerta.com.br\/index.php\/2026\/07\/14\/suspeitos-de-cometerem-homicidio-em-praca-publica-em-tucano-ba-sao-presos-durante-acao-conjunta-de-forcas-de-seguranca\/","title":{"rendered":"Suspeitos de cometerem homic\u00eddio em pra\u00e7a p\u00fablica em Tucano-BA, s\u00e3o presos durante a\u00e7\u00e3o conjunta de for\u00e7as de seguran\u00e7a"},"content":{"rendered":"\n<p>Uma a\u00e7\u00e3o conjunta da Pol\u00edcia Civil da Bahia, Pol\u00edcia Militar de Tucano e Guarda Civil Municipal de Tucano, por meio da equipe da ROMU (Ronda Ostensiva Municipal), resultou na pris\u00e3o de dois suspeitos investigados pelo homic\u00eddio qualificado de <a href=\"https:\/\/www.portalalerta.com.br\/index.php\/2026\/04\/08\/homem-e-assassinado-a-tiros-no-centro-de-tucano-ba\/\"><strong>Alisson Santos de Jesus, de 33 anos<\/strong><\/a>.<br><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>As pris\u00f5es foram realizadas na manh\u00e3 desta ter\u00e7a-feira, 14 de julho de 2026, em cumprimento a mandados de pris\u00e3o preventiva expedidos pela Justi\u00e7a, relacionados ao crime ocorrido no dia 7 de abril de 2026, na Pra\u00e7a da Caixa D\u2019\u00c1gua, no Centro do munic\u00edpio de Tucano<br><br>A a\u00e7\u00e3o foi coordenada pela 25\u00aa Coordenadoria Regional de Pol\u00edcia do Interior (25\u00aa Coorpin), com apoio da Pol\u00edcia Civil de Feira de Santana, equipes da DIRPIN Norte, Pol\u00edcia Militar (2\u00aa Cia) e Guarda Civil Municipal de Tucano.<br><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2026\/07\/julho-amarelo-Real-2026-576x1024.jpg\" alt=\"\" class=\"wp-image-80328\" style=\"width:391px;height:auto\" srcset=\"https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2026\/07\/julho-amarelo-Real-2026-576x1024.jpg 576w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2026\/07\/julho-amarelo-Real-2026-135x240.jpg 135w, https:\/\/www.portalalerta.com.br\/wp-content\/uploads\/2026\/07\/julho-amarelo-Real-2026.jpg 720w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure><\/div>\n\n\n<p><br>Um dos presos foi Marcos de Souza Pereira, conhecido como \u201cBinho\u201d, de 34 anos, localizado no munic\u00edpio de Feira de Santana. O segundo investigado, Jos\u00e9 Paulo Moreira Sousa, conhecido como \u201cZ\u00e9\u201d, de 33 anos, foi localizado e preso no povoado de Tiririca, zona rural de Tucano.<br><br>Segundo as investiga\u00e7\u00f5es conduzidas pela Pol\u00edcia Civil, os dois homens s\u00e3o apontados como autores do homic\u00eddio de Alisson Santos de Jesus, que participava de uma partida de futebol na quadra de esportes da Pra\u00e7a da Caixa D\u2019\u00c1gua quando foi surpreendido por dois indiv\u00edduos que chegaram ao local em uma motocicleta e efetuaram disparos de arma de fogo contra a v\u00edtima, que morreu ainda no local.<br><br>Os mandados de pris\u00e3o preventiva foram expedidos pela Vara Criminal da Comarca de Tucano, no \u00e2mbito do Processo n\u00ba 8000794-52.2026.8.05.0261, ap\u00f3s a Pol\u00edcia Civil reunir elementos que fundamentaram a representa\u00e7\u00e3o pelas pris\u00f5es.<br><br>Ap\u00f3s o cumprimento das ordens judiciais, os investigados foram apresentados \u00e0 autoridade policial para ado\u00e7\u00e3o das medidas legais e permanecem custodiados \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<br><br>As investiga\u00e7\u00f5es seguem em andamento com o objetivo de esclarecer completamente as circunst\u00e2ncias do crime.<br><br><em>Fonte: Gil Santos<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma a\u00e7\u00e3o conjunta da Pol\u00edcia Civil da Bahia, Pol\u00edcia Militar de Tucano e Guarda Civil Municipal de Tucano, por meio da equipe da ROMU (Ronda Ostensiva Municipal), resultou na pris\u00e3o de dois suspeitos investigados pelo homic\u00eddio qualificado de Alisson Santos de Jesus, de 33 anos.<\/p>\n","protected":false},"author":2,"featured_media":80450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[33,8473,69,32,22,12],"tags":[557,100,71,48,54,75,4178,4180,129,107,377,313,4181,2157,206,132,230,106,203,120,51,122,79,110,109,88,47,5467,111,190],"class_list":["post-80449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","category-destaque","category-noticias2","category-regiao","category-seguranca","category-tucano","tag-25a-coorpin","tag-adustina","tag-antas","tag-araci","tag-bahia","tag-cicero-dantas","tag-cipo-2","tag-crisopolis-2","tag-euclides-da-cunha","tag-fatima","tag-feira-de-santana","tag-gcm","tag-heliopolis-2","tag-homicidas","tag-homicidio","tag-itapicuru","tag-jeremoabo","tag-nova-soure","tag-novo-triunfo","tag-olindina","tag-paripiranga","tag-policia-civil","tag-policia-militar","tag-presos","tag-quijingue","tag-ribeira-do-amparo","tag-ribeira-do-pombal","tag-romu","tag-sitio-do-quinto","tag-tucano"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/80449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=80449"}],"version-history":[{"count":1,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/80449\/revisions"}],"predecessor-version":[{"id":80451,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/posts\/80449\/revisions\/80451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media\/80450"}],"wp:attachment":[{"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=80449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=80449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.portalalerta.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=80449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}